{"id":31963,"date":"2021-12-11T15:00:50","date_gmt":"2021-12-11T15:00:50","guid":{"rendered":"https:\/\/gogonihon.com\/?p=31963"},"modified":"2026-04-24T17:57:42","modified_gmt":"2026-04-24T08:57:42","slug":"cosa-pensano-gli-studenti-del-nostro-corso-di-giapponese-online","status":"publish","type":"post","link":"https:\/\/gogonihon.com\/it\/blog\/cosa-pensano-gli-studenti-del-nostro-corso-di-giapponese-online\/","title":{"rendered":"Cosa pensano gli studenti del nostro corso di giapponese online"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Abbiamo parlato con tre studenti che hanno completato il nostro corso di giapponese online per principianti di 12 settimane, a proposito della loro esperienza nel corso. Sono Antares dal Messico, Guillaume dalla Francia e Tanner dagli Stati Uniti.<\/span> <span style=\"font-weight: 400\">Scopri quanto sono migliorati in giapponese, cosa hanno trovato difficile nel corso e i loro consigli per la gestione del tempo mentre si frequenta un corso di lingua online.<\/span> <span style=\"font-weight: 400\">Nota che le risposte sono state modificate per chiarezza e brevit\u00e0.<\/span><\/p>\n<h3><b>Qual era il tuo livello di giapponese prima di iniziare il corso?<\/b><\/h3>\n<p><b>Antares<\/b><span style=\"font-weight: 400\">: Quasi zero. Tutto quello che sapevo veniva dagli <em>anime<\/em> e video su YouTube.<\/span><\/p>\n<p><b>Guillaume<\/b><span style=\"font-weight: 400\">: Quasi principiante. Conoscevo gi\u00e0 <em>hiragana, katakana<\/em> e qualche vocabolo grazie ai <a href=\"https:\/\/gogonihon.com\/it\/blog\/imparare-giapponese-dai-manga\/\"><em>manga<\/em><\/a> e <em><a href=\"https:\/\/gogonihon.com\/it\/blog\/imparare-giapponese-dagli-anime-frasi-e-vocaboli-utili\/\">anime<\/a>.<\/em><\/span><\/p>\n<p><b>Tanner<\/b><span style=\"font-weight: 400\">: Prima di iniziare il corso, avevo completato un corso di giapponese per principianti attraverso il mio Community College. Anche se ho imparato diverse cose e mi \u00e8 piaciuto molto imparare la lingua, la mancanza di pratica dopo i miei studi ha reso questo corso, che ho fatto pi\u00f9 di due anni fa, quasi obsoleto per quanto riguarda il mio attuale livello di conoscenza del giapponese.<\/span> <img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-83580 size-full\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2021\/11\/beginner-Japanese.jpg\" alt=\"Persona che sta studiando i kanji con una tabella, un caff\u00e8, una penna e degli snack sul tavolo\" width=\"798\" height=\"436\" \/><\/p>\n<h3><b>Cosa ti \u00e8 piaciuto di pi\u00f9 del nostro corso online di giapponese per principianti?<\/b><\/h3>\n<p><b>Antares<\/b><span style=\"font-weight: 400\">: Il fatto che ho potuto seguire i miei tempi e che \u00e8 stato, in un certo senso, personale.<\/span><\/p>\n<p><b>Guillaume<\/b><span style=\"font-weight: 400\">: Il modo in cui sono fatte le lezioni \u00e8 molto interessante e le cose vengono spiegate perfettamente in modo da capirle molto pi\u00f9 velocemente.<\/span><\/p>\n<p><b>Tanner<\/b><span style=\"font-weight: 400\">: Mi ha dato una conoscenza del giapponese che ho sentito immediatamente utilizzabile. Quello che ho imparato attraverso il corso non erano solo le basi della lingua o le prime nozioni di grammatica per formare frasi. Questo corso mi ha dato gli strumenti necessari da iniziare a utilizzare mentre sono ancora in America, in attesa di andare in Giappone.<\/span><\/p>\n<h3><b>Cosa avete trovato pi\u00f9 impegnativo?<\/b><\/h3>\n<p><b>Antares<\/b><span style=\"font-weight: 400\">: Dato che non c&#8217;erano &#8220;obblighi&#8221;, a volte mi dimenticavo del corso e lo lasciavo l\u00ec per giorni. Quindi ho dovuto concentrarmi molto sui miei studi e stabilire degli orari. A parte questo, \u00e8 un corso abbastanza semplice e diretto.<\/span><\/p>\n<p><b>Guillaume:<\/b><span style=\"font-weight: 400\"> Memorizzare un sacco di vocaboli in poco tempo. I <em>kanji<\/em> sono anche molto difficili da memorizzare, ma questo rende l&#8217;apprendimento pi\u00f9 divertente e stimolante.<\/span><\/p>\n<p><b>Tanner<\/b><span style=\"font-weight: 400\">: L&#8217;aspetto pi\u00f9 impegnativo del corso per me \u00e8 stato applicare ci\u00f2 che stavo imparando nella mia vita quotidiana. \u00c8 stata una delle mie parti preferite! Dove vivo, ho l&#8217;incredibile opportunit\u00e0 di essere vicino a cos\u00ec tanti ristoranti e attivit\u00e0 commerciali giapponesi cos\u00ec da poter praticare le mie abilit\u00e0 linguistiche.<\/span><\/p>\n<h3><b>Come hai gestito il tuo tempo mentre seguivi il corso?<\/b><\/h3>\n<p><b>Antares<\/b><span style=\"font-weight: 400\">: Avevo un lavoro part-time, quindi a volte mi dimenticavo delle mie lezioni perch\u00e9 ero stanco o semplicemente non avevo voglia di seguire le lezioni quel giorno. Tuttavia, il corso mi ha aiutato a distrarmi dalla mia routine quotidiana, quindi ho cercato di seguirlo ogni pomeriggio, almeno per 30 minuti al giorno.<\/span><\/p>\n<p><b>Guillaume<\/b><span style=\"font-weight: 400\">: Quando ho iniziato il corso di giapponese online per principianti, era la mia priorit\u00e0 ogni giorno. Passavo circa due ore al mattino a eseguire le lezioni. Nel pomeriggio facevo i compiti e rileggevo le lezioni. Durante l&#8217;intero periodo avevo forse due o tre settimane di vacanza. Ma quando avevo tempo libero rileggevo le lezioni.<\/span> <span style=\"font-weight: 400\">Al di fuori delle lezioni, ho comprato dei libri di esercizi per allenarmi un po&#8217; di pi\u00f9 rispetto al corso. Ho anche comprato un quaderno di kanji e un dizionario di kanji che uso ancora dopo aver finito il corso.<\/span><\/p>\n<p><b>Tanner<\/b><span style=\"font-weight: 400\">: Mi \u00e8 stato facile gestire il lavoro a tempo pieno e la mia vita sociale mentre completavo tutte le lezioni. Ho creato il mio &#8220;programma scolastico&#8221;, dandomi cinque giorni da dedicare completamente al corso online e due giorni per rivedere ci\u00f2 che ho imparato.<\/span> <span style=\"font-weight: 400\">Al di fuori del tempo trascorso a seguire il corso, uno dei miei obiettivi pi\u00f9 grandi \u00e8 stato quello di passare almeno un&#8217;ora ogni giorno a rivedere ci\u00f2 che avevo imparato. Ho passato un po&#8217; di tempo a rivedere i miei appunti a cena o a interrogarmi sulla struttura delle frasi con un po&#8217; di musica in sottofondo. Soprattutto, prima di andare a letto studiavo le <em>flash-cards<\/em> con i nuovi vocaboli, la parte con cui ho avuto pi\u00f9 difficolt\u00e0.<\/span><\/p>\n<h3><b>Quanto pensi sia migliorata la tua capacit\u00e0 di parlare giapponese alla fine del corso?<\/b><\/h3>\n<p><b>Antares<\/b><span style=\"font-weight: 400\">: Penso che le mie capacit\u00e0 linguistiche siano migliorate. Tuttavia, personalmente avrei potuto dedicare pi\u00f9 tempo e impegno ai miei studi per essere ad un livello pi\u00f9 alto di quello attuale.<\/span><\/p>\n<p><b>Guillaume<\/b><span style=\"font-weight: 400\">: Credo che le mie competenze siano davvero migliorate alla fine del corso e probabilmente ora sono in grado di andare in Giappone e di farmi capire, almeno per le cose pi\u00f9 semplici. Forse il mio modo di parlare non \u00e8 affatto fluido, ma pi\u00f9 vocabolario conosco, pi\u00f9 posso dire o chiedere cose.<\/span><\/p>\n<p><b>Tanner<\/b><span style=\"font-weight: 400\">: Il mio giapponese \u00e8 migliorato immensamente grazie a questo corso. Una delle mie pi\u00f9 grandi paure quando ho completato il processo di applicazione per la scuola di lingua in Giappone, era da dove iniziare quando si trattava di re-imparare anche solo il giapponese da principiante che avevo una volta. Dodici settimane non sono assolutamente sufficienti per diventare fluente in giapponese, ma ho pi\u00f9 fiducia nell&#8217;imparare la lingua in futuro.<\/span> <img decoding=\"async\" class=\"alignnone wp-image-83590 size-full\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2021\/11\/online-course.jpg\" alt=\"Persona che studia con il corso di giapponese online Akamonkai dal computer\" width=\"798\" height=\"436\" \/><\/p>\n<h3><b>Cosa stai facendo in termini di studi linguistici ora che hai finito il corso?<\/b><\/h3>\n<p><b>Antares<\/b><span style=\"font-weight: 400\">: Cerco di esercitarmi ogni giorno con i video di YouTube, seguo gli account di TikTok che mi ricordano il vocabolario ogni giorno e seguo gli influencer giapponesi per non dimenticare ci\u00f2 che gi\u00e0 so. Attualmente sto cercando di andare a Osaka per proseguire i miei studi di lingua giapponese in modo da poter costruire il mio futuro in Giappone.<\/span><\/p>\n<p><b>Guillaume<\/b><span style=\"font-weight: 400\">: Dopo aver finito il mio corso, ho continuato a studiare giapponese per conto mio perch\u00e9 sono ancora un principiante e ho bisogno di lavorare ogni giorno per migliorare. In futuro, spero di conoscere meglio la cultura giapponese e di farmi degli amici l\u00ec. Il mio obiettivo \u00e8 quello di imparare la scrittura giapponese per scrivere il mio manga e, se possibile, imparare qualche tecnica di disegno mentre sono in Giappone.<\/span><\/p>\n<p><b>Tanner<\/b><span style=\"font-weight: 400\">: Dopo aver finito il corso ho concentrato la maggior parte dei miei studi nell&#8217;imparare pi\u00f9 kanji da un libro di lavoro che ho acquistato online. Cerco anche di prendere qualche kanji da qualsiasi manga stia leggendo o traducendo dal giapponese all&#8217;inglese.<\/span> <span style=\"font-weight: 400\">Ho anche acquistato il <\/span><a href=\"https:\/\/gogonihon.com\/it\/corsi-online\/online\/japanese-crash-course\/\"><b>Go! Go! Nihon Japanese Crash Course<\/b><\/a><span style=\"font-weight: 400\">. Sono stata particolarmente attratta da questo corso perch\u00e9 trattava il giapponese per principianti, ma anche per la sua attenzione alla cultura giapponese. Mi \u00e8 piaciuta molto la lezione che discuteva la storia dell&#8217;<a href=\"https:\/\/gogonihon.com\/it\/blog\/cultura-del-bere-in-giappone\/\">alcool giapponese<\/a> e che terminava con la visita ad una fabbrica di <em>sake<\/em>. Raccomando caldamente anche questo corso perch\u00e9 non solo \u00e8 stato un buon corso intensivo, ma \u00e8 stato anche super interessante e ho imparato molto di pi\u00f9 sulla cultura e le tradizioni giapponesi di quanto pensassi.<\/span><\/p>\n<h3><b>Quali sono i vostri migliori consigli per imparare online?<\/b><\/h3>\n<p><b>Antares<\/b><span style=\"font-weight: 400\">: Questo \u00e8 un momento difficile per tutti noi e stiamo tutti cercando qualcosa per distrarci. Imparare una nuova lingua \u00e8 fantastico! I miei consigli sono: fallo con i tuoi tempi e quando pensi che sia meglio per te, senza avere troppa pressione. Dovresti goderti l&#8217;apprendimento di una lingua, non soffrire per questo.<\/span> <span style=\"font-weight: 400\">Costruisci un programma che sia giusto per te e lavora con quello. Potrebbe essere la mattina o il pomeriggio. Se sei una persona impegnata, dedica almeno 30 minuti al giorno. La coerenza \u00e8 la chiave. Ripeti tra te e te il vocabolario. Quando ti senti sopraffatto, fai una pausa. Mantieni i tuoi appunti semplici. Non devi scrivere tutto, a meno che non funzioni per te.<\/span> <span style=\"font-weight: 400\">Infine, il consiglio che ha funzionato meglio per me \u00e8: guarda, leggi, ascolta in giapponese il pi\u00f9 possibile. Guarda anime, reality TV, Vlogger di YouTube e ascolta <a href=\"https:\/\/gogonihon.com\/it\/blog\/guida-al-j-pop-la-musica-pop-giapponese\/\">musica giapponese<\/a>. Se programmi il tuo cervello per ascoltare la lingua, anche nel tempo libero, imparare la lingua sar\u00e0 davvero facile.<\/span><\/p>\n<p><b>Guillaume<\/b><span style=\"font-weight: 400\">: Imparare una lingua \u00e8 qualcosa che richiede tempo e deve essere fatto ogni giorno, anche per un breve periodo. Imparare online \u00e8 fantastico, ma non c\u2019\u00e8 nessuno dietro di te che ti dice di continuare a lavorare, quindi devi essere motivato. Trova un obiettivo da raggiungere e lavora al di fuori del corso; non solo i compiti ma anche leggere, fare esercizi, guardare o ascoltare un po&#8217; di giapponese. <\/span><span style=\"font-weight: 400\">Imparare il giapponese \u00e8 davvero interessante, quindi non dovresti forzarti ad impararlo ma divertirti a farlo.<\/span><\/p>\n<p><b>Tanner<\/b><span style=\"font-weight: 400\">: Raccomando vivamente di gestire il proprio tempo con un programma, eliminare le distrazioni da dove si studia, ecc. Ma il mio pi\u00f9 grande consiglio per questo corso e per lo studio del giapponese in generale \u00e8 di divertirsi. Imparare il giapponese \u00e8 davvero divertente, ma studiare qualsiasi cosa in un formato di classe o online pu\u00f2 diventare difficile.\u00a0 Penso che sia essenziale continuare a divertirsi con il giapponese e trovare modi divertenti per continuare a imparare e applicare ci\u00f2 che si \u00e8 gi\u00e0 imparato al di fuori dei corsi online.<\/span> <span style=\"font-weight: 400\">Uno dei miei nuovi hobby preferiti \u00e8 leggere manga in giapponese e tradurli in inglese. Non solo \u00e8 divertente, ma tendo ad assorbire molto di ci\u00f2 che imparo. Questo significa che non solo mi sto divertendo, ma sto anche studiando tecnicamente! Imparare una nuova lingua non dovrebbe mai essere noioso, ma sta nelle mani di chi sta imparando renderlo il pi\u00f9 divertente possibile.<\/span><\/p>\n<p><b>Per saperne di pi\u00f9 sul corso di giapponese online per principianti di 12 settimane, clicca<\/b><a href=\"https:\/\/japaneseonline.gogonihon.com\/courses\/akamonkai-japanese-12-week-beginner-course\"> <b>qui<\/b><\/a><b>. Se non sei sicuro del tuo livello linguistico, fai il nostro test<\/b><a href=\"https:\/\/japaneseonline.gogonihon.com\/pages\/level-check-test\"> <b>qui<\/b><\/a><b>.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo parlato con tre studenti che hanno completato il nostro corso di giapponese online per principianti di 12 settimane, a proposito della loro esperienza nel corso. Sono Antares dal Messico, Guillaume dalla Francia e Tanner dagli Stati Uniti. Scopri quanto sono migliorati in giapponese, cosa hanno trovato difficile nel corso e i loro consigli per [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":26346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[429],"tags":[824],"class_list":["post-31963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imparare-giapponese","tag-corsi-online"],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts\/31963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/comments?post=31963"}],"version-history":[{"count":1,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts\/31963\/revisions"}],"predecessor-version":[{"id":214104,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts\/31963\/revisions\/214104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/media\/26346"}],"wp:attachment":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/media?parent=31963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/categories?post=31963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/tags?post=31963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}