{"id":31703,"date":"2024-08-03T19:00:00","date_gmt":"2024-08-03T10:00:00","guid":{"rendered":"https:\/\/gogonihon.com\/?p=31703"},"modified":"2024-08-07T16:08:11","modified_gmt":"2024-08-07T07:08:11","slug":"buddhismo-in-giappone","status":"publish","type":"post","link":"https:\/\/gogonihon.com\/it\/blog\/buddhismo-in-giappone\/","title":{"rendered":"Introduzione del buddhismo in Giappone"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il buddhismo \u00e8 uno dei due principali culti in Giappone, che ha convissuto con la sua controparte, lo Shintoismo, per molti secoli. Il buddhismo \u00e8 stato ufficialmente portato in Giappone da Cina e Corea durante il 6\u00b0 secolo come<\/span><b> dono di pace tra le nazioni. <\/b><span style=\"font-weight: 400\">L\u2019arrivo del buddhismo in Giappone ha portato con s\u00e9 anche un nuovo sistema di scrittura, una struttura politica, la superiorit\u00e0 tecnologica e delle pratiche culturali sofisticate apprezzate da nobili e aristocratici.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">In questo articolo vogliamo darti un\u2019idea generale della storia del buddhismo in Giappone, con le sue sette principali ed i rituali associati alla societ\u00e0 contemporanea. Continua a leggere se vuoi saperne di pi\u00f9.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Origini del buddhismo in Giappone<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Inizialmente introdotto come dono di benevolenza tra nazioni, non \u00e8 difficile comprendere perch\u00e9 il buddhismo in Giappone si sia inizialmente diffuso tra nobili e aristocratici. In base al <\/span><i><span style=\"font-weight: 400\">Nihon Shoki<\/span><\/i><span style=\"font-weight: 400\"> (\u65e5\u672c\u66f8\u7d00, Cronache giapponesi), il secondo pi\u00f9 antico documento storico in Giappone, il buddhismo sarebbe stato introdotto nel 552. La leggenda narra che l\u2019imperatore giapponese si consult\u00f2 con i suoi ufficiali per decidere se il buddhismo dovesse essere praticato o meno in Giappone. Ci fu sulla questione, per timore dell\u2019ira dei <\/span><i><span style=\"font-weight: 400\">Kami<\/span><\/i><span style=\"font-weight: 400\">, o<\/span><a href=\"https:\/\/gogonihon.com\/it\/blog\/culto-shinto-in-giappone\/\"><span style=\"font-weight: 400\"> divinit\u00e0 Shint\u014d<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">La soluzione fu che il clan Soga fosse il primo a praticare il buddhismo per vedere com\u2019era recepito. Il clan Soga era il gruppo aristocratico pi\u00f9 potente dell\u2019epoca con delle strette connessioni con la Casa imperiale e che gioc\u00f2 un ruolo chiave nella diffusione del buddhismo in Giappone nella prima fase.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Inizialmente sono stati accolti con resistenza dalle varie fazioni che incolpavano il buddhismo di essere portatore di malattie e di sfortuna. Tuttavia, dal trambusto che ne segu\u00ec il clan Soga emerse vittorioso e promosse il buddhismo con il sostegno della corte imperiale.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Sin da allora il buddhismo ha sempre giocato un ruolo chiave nella storia giapponese e una forte influenza politica. Durante il periodo Nara (710-794) il tempio pi\u00f9 imponente <\/span><i><span style=\"font-weight: 400\">T\u014ddaiji<\/span><\/i><span style=\"font-weight: 400\"> \u6771\u5927\u5bfa divenne il centro del buddhismo in Giappone. L\u2019influenza politica del buddhismo divenne il motivo per cui la capitale fu spostata a <\/span><i><span style=\"font-weight: 400\">Heian-Ky\u014d<\/span><\/i><span style=\"font-weight: 400\"> \u5e73\u5b89\u4eac(la moderna Kyoto).<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/02\/statues-outside-of-temple.jpg\" alt=\"Immagini di statue di Buddha fuori da un tempio giapponese\" class=\"wp-image-98216\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Scuole di buddhismo e templi associati<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Durante gli anni il buddhismo in Giappone si \u00e8 evoluto, cambiando e collegandosi con lo Shint\u014dismo in maniera complicata. Oggi ci sono sei principali rami del buddhismo in Giappone: Nara, Tendai, Shingon, Amida (Pure Land), Nichiren e Zen.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>Buddhismo Zen&nbsp;<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">La caratteristica principale del buddhismo Zen \u00e8 il focus sulla meditazione da seduti o <\/span><i><span style=\"font-weight: 400\">zazen<\/span><\/i><span style=\"font-weight: 400\"> (\u5ea7\u7985) per poter diventare illuminati. Il buddhismo Zen \u00e8 probabilmente la pi\u00f9 popolare forma di buddhismo conosciuta nei paesi occidentali per via del boom culturale della meditazione zen.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Un tempio dove puoi provare la vera meditazione zen e immergerti nel vuoto di te stesso \u00e8 il tempio <\/span><i><span style=\"font-weight: 400\">Nanzenji <\/span><\/i><span style=\"font-weight: 400\">(\u5357\u7985\u5bfa) di Kyoto.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>Buddhismo Nara&nbsp;<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il buddhismo Nara fa riferimento a sei diverse scuole di buddhismo in Giappone che sono state ufficialmente sponsorizzate durante il periodo Nara. Tra queste, tre sono sopravvissute oggi, ma sono diventate molto meno influenti da quando la capitale \u00e8 stata spostata a Heian-Ky\u014d.\u00a0<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il tempio principale del buddhismo di Nara \u00e8 il T\u014ddaiji (\u6771\u5927\u5bfa), il pi\u00f9 grande tempio in legno di tutto il mondo e dall\u2019aspetto spettacolare se visiterai la <\/span><a href=\"https:\/\/gogonihon.com\/it\/blog\/citta-di-nara\/\"><span style=\"font-weight: 400\">citt\u00e0 di Nara<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"798\" height=\"436\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2024\/08\/Buddhismo-in-Giappone-1.png\" alt=\"\" class=\"wp-image-123859\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2024\/08\/Buddhismo-in-Giappone-1.png 798w, https:\/\/gogonihon.com\/wp-content\/uploads\/2024\/08\/Buddhismo-in-Giappone-1-300x164.png 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2024\/08\/Buddhismo-in-Giappone-1-768x420.png 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><b>Buddhismo Tendai&nbsp;<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il fondatore del buddhismo Tendai in Giappone, <\/span><i><span style=\"font-weight: 400\">Saich\u014d<\/span><\/i><span style=\"font-weight: 400\"> \u6700\u6f84, promise di proteggere la capitale e anche la nazione giapponese. Il monaco buddhista costru\u00ec il nuovo complesso del tempio sulla cima della montagna Hiei (\u6bd4\u53e1\u5c71 <\/span><i><span style=\"font-weight: 400\">Hieizan<\/span><\/i><span style=\"font-weight: 400\">).&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il buddhismo Tendai si focalizza sull\u2019\u2019illuminazione di tutti\u201d e ha creato le fondamenta di quello che la maggior parte delle figure buddhiste del Giappone hanno studiato a un certo punto della loro carriera.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>Buddhismo Shingon&nbsp;<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Secondo il buddhismo Shingon la vera illuminazione non pu\u00f2 essere raggiunta solo studiando e c\u2019\u00e8 un forte accento sulla meditazione con invocazioni speciali, posizioni delle mani elaborate e mandala (simbolo dell\u2019universo nella sua forma ideale).<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il fondatore <\/span><i><span style=\"font-weight: 400\">K\u016bkai<\/span><\/i><span style=\"font-weight: 400\"> \u7a7a\u6d77 stabil\u00ec il centro di questa nuova forma di buddhismo sulla cima della montagna K\u014dya (\u9ad8\u91ce\u5c71 <\/span><i><span style=\"font-weight: 400\">K\u014dyasan<\/span><\/i><span style=\"font-weight: 400\">). Fu nominato abbate del tempio principale <\/span><i><span style=\"font-weight: 400\">T\u014dji<\/span><\/i><span style=\"font-weight: 400\"> (\u6771\u5bfa).&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il monte K\u014dya \u00e8 uno dei posti pi\u00f9 suggestivi che puoi visitare in Giappone e te lo consigliamo fortemente anche se non sei particolarmente interessato alla storia giapponese.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>Buddhismo Amida (Terra pura)&nbsp;<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">C\u2019erano due sette Amida a Heian-Ky\u014d alla fine del periodo Heian. Queste erano <\/span><i><span style=\"font-weight: 400\">J\u014ddo-sh\u016b<\/span><\/i><span style=\"font-weight: 400\"> \u6d44\u571f\u5b97 e J\u014ddoshin-sh\u016b \u6d44\u571f\u771f\u5b97. Il fondatore J\u014ddo-sh\u016b, H\u014dnen \u6cd5\u7136 e il suo studente <\/span><i><span style=\"font-weight: 400\">Shinran<\/span><\/i><span style=\"font-weight: 400\"> \u89aa\u9e1e hanno studiato all\u2019Enryakuji, ma pensavano che la severa autodisciplina dei precedenti insegnamenti buddhisti fosse troppo per dei comuni mortali.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Di conseguenza fondarono una nuova setta che prometteva l\u2019illuminazione semplicemente ripetendo tre parole <\/span><i><span style=\"font-weight: 400\">Namu Amida Butsu<\/span><\/i><span style=\"font-weight: 400\"> (\u5357\u7121\u963f\u5f25\u9640\u4ecf, Mi rifugio nel buddha Amida). Questa nuova religione divenne immensamente popolare perch\u00e9 era accessibile a tutti e non era solo aristocratica.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">I templi associati sono <\/span><i><span style=\"font-weight: 400\">Chion-in<\/span><\/i><span style=\"font-weight: 400\"> (\u77e5\u6069\u9662), <\/span><i><span style=\"font-weight: 400\">Nishi-Honganji<\/span><\/i><span style=\"font-weight: 400\"> (\u897f\u672c\u9858\u5bfa) e <\/span><i><span style=\"font-weight: 400\">Higashi-Honganji<\/span><\/i><span style=\"font-weight: 400\"> (\u6771\u672c\u9858\u5bfa), tutti templi degni di nota nella zona di Kyoto e decisamente meritevoli di una visita.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>Buddhismo Nichiren&nbsp;<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il buddhismo Nichiren \u00e8 stata la risposta di un gruppo di persone non contente delle nuove sette di terra pura del buddhismo. Hanno attivamente creato inimicizie con le altre sette proclamando che l\u2019unico vero insegnamento per raggiungere l\u2019illuminazione era attraverso il buddhismo Nichiren e con le letture sacre del Sutra del Loto. In un attimo si trovarono in guerra con i monaci guerrieri dell\u2019Enryakuji e furono sconfitti in una battaglia che ridusse in cenere la citt\u00e0 di Kyoto.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Nonostante fossero state sradicate una volta, oggi le sette Nichiren sono tornate e ci sono numerosi templi associati in Giappone.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><img decoding=\"async\" class=\"alignnone size-full wp-image-98227\" style=\"font-size: 16px\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/02\/Setsubun.jpg\" alt=\"Image of items on display for setsubun celebrations\" width=\"798\" height=\"436\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Riti associati e celebrazioni<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Hai mai visto uno spettacolo in cui i bambini aprono la porta d\u2019ingresso e gettano fagioli di soia mentre pronunciano la frase \u201c<\/span><i><span style=\"font-weight: 400\">Oni wa soto, fuku wa uchi<\/span><\/i><span style=\"font-weight: 400\">\u201d (\u9b3c\u306f\u5916\u798f\u306f\u5185, demone fuori fortuna dentro)?&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Si tratta del tradizionale <\/span><i><span style=\"font-weight: 400\">mamemaki<\/span><\/i><span style=\"font-weight: 400\"> (\u8c46\u6492\u304d, lancio dei fagioli) popolare durante la vacanza buddhista di <\/span><i><span style=\"font-weight: 400\">setsubun<\/span><\/i><span style=\"font-weight: 400\"> \u7bc0\u5206 che si svolge tra il 2 e il 4 febbraio.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Un\u2019altro rituale associato al buddhismo in Giappone \u00e8 l\u2019<\/span><a href=\"https:\/\/gogonihon.com\/it\/blog\/che-cose-lobon\/\"><i><span style=\"font-weight: 400\">Obon<\/span><\/i><span style=\"font-weight: 400\"> (\u304a\u76c6)<\/span><\/a><span style=\"font-weight: 400\">. Si dice che gli spiriti dei parenti tornino per far visita durante l\u2019estate e per questo motivo ci sono grandi festival con danze e lanterne per guidare gli spiriti. Alla fine dei tre giorni di obon si lasciano andare le lanterne sull\u2019acqua del fiume nella cerimonia del <\/span><i><span style=\"font-weight: 400\">toro-nagashi<\/span><\/i><span style=\"font-weight: 400\"> (\u3068\u308d\u6d41\u3057, lanterne galleggianti). Simboleggia il ritorno degli spiriti al loro mondo.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Il buddhismo nel Giappone moderno<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Il buddhismo ha senza dubbio avuto un grande impatto sulla societ\u00e0 giapponese attraverso i secoli. Sebbene molti giovani giapponesi non siano veri credenti, le abitudini religiose come la visita ai templi e la preghiera per una salute prosperosa restano attivit\u00e0 popolari svolte da quasi tutti i giapponesi.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Altri segni del significato del buddhismo in Giappone sono le case tradizionali giapponesi, equipaggiate di un altare buddhista, chiamato <\/span><i><span style=\"font-weight: 400\">butsudan <\/span><\/i><span style=\"font-weight: 400\">(\u4ecf\u58c7), e il fatto che la maggior parte dei funerali <\/span><i><span style=\"font-weight: 400\">os\u014dshiki<\/span><\/i><span style=\"font-weight: 400\"> (\u304a\u846c\u5f0f) seguano la maniera buddhista.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Speriamo che questo articolo sul buddhismo in Giappone sia stato interessante. Se vuoi saperne di pi\u00f9 sulla cultura giapponese e la vita in Giappone segui il <\/b><a href=\"https:\/\/gogonihon.com\/it\/blog\/\"><b>nostro blog<\/b><\/a><b>.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il buddhismo \u00e8 uno dei due principali culti in Giappone, che ha convissuto con la sua controparte, lo Shintoismo, per molti secoli. Il buddhismo \u00e8 stato ufficialmente portato in Giappone da Cina e Corea durante il 6\u00b0 secolo come dono di pace tra le nazioni. L\u2019arrivo del buddhismo in Giappone ha portato con s\u00e9 anche [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":25425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[425],"tags":[838,840],"class_list":["post-31703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-giapponese","tag-cultura","tag-storia"],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts\/31703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/comments?post=31703"}],"version-history":[{"count":0,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts\/31703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/media\/25425"}],"wp:attachment":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/media?parent=31703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/categories?post=31703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/tags?post=31703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}