{"id":111157,"date":"2023-11-09T06:00:00","date_gmt":"2023-11-08T21:00:00","guid":{"rendered":"https:\/\/gogonihon.com\/?p=111157"},"modified":"2024-08-07T09:15:41","modified_gmt":"2024-08-07T00:15:41","slug":"il-teatro-kabuki-in-giappone","status":"publish","type":"post","link":"https:\/\/gogonihon.com\/it\/blog\/il-teatro-kabuki-in-giappone\/","title":{"rendered":"Un&#8217;introduzione del teatro kabuki in Giappone"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il teatro kabuki in Giappone \u00e8 una delle pi\u00f9 grandi espressioni artistiche, con una lunga e ricca storia che risale a oltre 400 anni fa. Nel corso della storia, il kabuki ha attraversato molte trasformazioni e riforme. Tuttavia, sostenuto da numerosi appassionati e dagli straordinari sforzi di attori e produttori che continuano a rappresentare spettacoli tradizionali e a creare nuove opere, esso occupa un posto significativo nella cultura giapponese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo articolo ti dar\u00e0 un&#8217;introduzione del teatro kabuki in Giappone per conoscere pi\u00f9 a fondo la bellezza di questa cultura tradizionale giapponese!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"798\" height=\"436\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-roof.jpg\" alt=\"Intricato tetto del teatro Kabukiza che ospita gli spettacoli di Kabuki in Giappone\" class=\"wp-image-110735\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-roof.jpg 798w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-roof-300x164.jpg 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-roof-768x420.jpg 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong>Una curiosit\u00e0: le donne hanno iniziato il kabuki, ma al giorno d&#8217;oggi solo gli uomini lo praticano.<\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;origine del kabuki in Giappone risale al diciassettesimo secolo a Kyoto, quando una donna che si faceva chiamare &#8220;vergine del santuario&#8221;, <em>Izumo no okuni<\/em>, inizi\u00f2 a ballare in pubblico. Si dice che imitasse un gruppo di uomini chiamati &#8220;kabukimono&#8221; che attiravano l&#8217;attenzione pubblica con l&#8217;aspetto vistoso e movimenti insoliti. La danza di <em>Izumo no okuni<\/em> fu chiamata <strong>kabuki-odori<\/strong> (&#8220;<em>odori<\/em>&#8221; significa danza) e divenne molto popolare. Influenzate dalla popolarit\u00e0 della kabuki-odori, molte altre donne iniziarono a ballare, il che lo rese ancora pi\u00f9 famoso con il nome di <em>onna-kabuki<\/em> (&#8220;danza della donna&#8221;).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuttavia, le autorit\u00e0 dell&#8217;epoca credevano che l&#8217;<em>onna-kabuki<\/em> potesse distruggere la morale pubblica e per questo lo bandirono. Questa forma d&#8217;arte era, per\u00f2, gi\u00e0 cos\u00ec popolare che la gente cerc\u00f2 in qualche modo di preservarla. \u00c8 a questo punto che gruppi di <strong>giovani uomini <\/strong>scesero in campo (<em>wakashu-kabuki<\/em>). Nonostante ci\u00f2, man mano che guadagnava popolarit\u00e0, il pubblico inizi\u00f2 a litigare per i propri attori preferiti, e di nuovo, le autorit\u00e0 bandirono quei giovani uomini dal praticare il kabuki. Ma la storia non fin\u00ec l\u00ec. Dopo che le autorit\u00e0 proibirono ai giovani uomini di praticare il kabuki, gruppi di uomini pi\u00f9 anziani iniziarono a praticarlo (<em>yaro-kabuki<\/em>). Con lo sviluppo del yaro-kabuki, esso divenne una forma artistica pi\u00f9 consolidata con vari ruoli interpretati da uomini, che continuano a essere una delle caratteristiche uniche del kabuki.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per saperne di pi\u00f9, comprese informazioni su dove e come sperimentare il kabuki in Giappone o all&#8217;estero, continua a leggere!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Spettacoli di kabuki<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nel teatro kabuki esistono <strong>spettacoli tradizionali chiamati <em>koten<\/em> e nuovi spettacoli chiamati <em>shinsaku<\/em>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quindi, che tipo di storie vengono rappresentate nei kabuki <em>koten<\/em> (i tradizionali)? Ci sono tre tipi di spettacoli nei <em>kabuki koten<\/em>: <em>jidaimono<\/em>, <em>sewamono<\/em> e <em>shosagoto<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jidaimono<\/strong> \u00e8 uno spettacolo storico che tratta eventi accaduti nel passato. <strong>Sewamono<\/strong> \u00e8 uno spettacolo contemporaneo che si concentra sulla vita delle persone comuni, come drammi familiari, relazioni, ecc. <strong>Shosagoto <\/strong>\u00e8 uno spettacolo di danza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quale di questi \u00e8 pi\u00f9 adatto ai neofiti?<\/strong> In confronto a <em>jidaimono<\/em> e <em>sewamono<\/em>, che includono molte referenze culturali e dialoghi in giapponese tradizionale, lo <em>shosagoto<\/em> \u00e8 principalmente una danza. Quindi, se sei un neofita, ti consigliamo di guardare uno spettacolo di shosagoto. Sarai sorpreso dalla delicatezza della danza e potrai apprezzare la musica tradizionale e i bellissimi costumi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D&#8217;altro canto, il kabuki <\/strong><strong><em>shinsaku <\/em><\/strong><strong>(nuovo) pu\u00f2 essere qualsiasi cosa!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ad esempio, negli ultimi anni il kabuki ha adottato &#8220;Nausicaa della Valle del Vento&#8221; dello Studio Ghibli e &#8220;Final Fantasy X&#8221; per invitare un pubblico pi\u00f9 variegato al teatro. Inoltre, esiste un tipo di kabuki in Giappone chiamato &#8220;<strong>Super kabuki<\/strong>&#8220;, creato nell&#8217;era Showa da Ichikawa Ennosuke III, che incorpora tecniche e stili pi\u00f9 moderni, come la <strong>musica pop contemporanea<\/strong> ed effetti sonori. Suo nipote, Ichikawa Ennosuke IV, ha avuto successo nell&#8217;invitare un pubblico pi\u00f9 giovane al teatro. Il Super kabuki pi\u00f9 famoso degli ultimi anni \u00e8 <strong>One Piece Kabuki<\/strong>, che ha riadattato la popolare serie manga One Piece.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Come godersi uno spettacolo di kabuki?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ci sono molti modi diversi per godersi uno spettacolo di kabuki in Giappone, e il modo in cui questo avviene dipende da ogni spettatore. Tuttavia, in generale, ci sono diverse caratteristiche del kabuki che affascinano il pubblico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Musica ed effetti sonori<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi ascoltare con piacere la musica del kabuki, con lo <em>shamisen<\/em>, il <em><a href=\"https:\/\/gogonihon.com\/it\/blog\/storia-dei-tamburi-giapponesi-taiko-tra-ritmo-e-tradizione\/\" data-type=\"post\" data-id=\"32202\">taiko<\/a><\/em> (tamburo) e il <em>nagauta<\/em> (canzoni tradizionali accompagnate dalla musica dello shamisen). Inoltre, i battenti di legno chiamati <em>tsuke<\/em> aggiungono effetti sonori a scene cruciali, come l&#8217;ingresso, le lotte e le uscite degli attori. Il suono degli <em>tsuke<\/em> \u00e8 specifico del kabuki in Giappone e aggiunge dinamicit\u00e0 all&#8217;interpretazione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Performance<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Naturalmente, le performance degli attori sono spettacolari. Molti di loro hanno ricevuto formazione fin dall&#8217;infanzia, il che gli permette di eseguire performance complesse con successo. Alcuni esempi delle tecniche splendide che utilizzano durante le performance sono l&#8217;<em>Hayagawari<\/em> (cambio rapido dei costumi) e il <em>Roppo<\/em> (camminata stilizzata drammatica). In alcune rappresentazioni, gli attori volano sopra il pubblico eseguendo il <em>chunori<\/em> (performance in aria)! Vale la pena vedere il kabuki in Giappone almeno una volta nella vita.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"798\" height=\"436\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabuki-actors.jpg\" alt=\"Insegna di attori di kabuki in Giappone che indossano il tipico trucco bianco.\" class=\"wp-image-110743\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabuki-actors.jpg 798w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabuki-actors-300x164.jpg 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabuki-actors-768x420.jpg 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Costumi<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 affascinante osservare una variet\u00e0 di costumi nelle rappresentazioni del kabuki. Gli stilisti creano costumi specifici per ciascuna storia con dettagli incredibili che aggiungono bellezza alla narrazione. A seconda della stagione di uno spettacolo, \u00e8 possibile osservare diversi motivi e fiori sui loro splendidi kimono!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trucco<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il trucco unico del kabuki si chiama <strong>kumadori<\/strong>, e in base al colore e al motivo del kumadori \u00e8 possibile capire se quel personaggio \u00e8 un eroe, un cattivo, un nobile o non umano!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il rosso esprime potere, un senso di giustizia, giovinezza o rabbia. Il blu rappresenta cattivi o fantasmi vendicativi. Il marrone rappresenta demoni e fantasmi (non umani).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli attori dipingevano originariamente il loro volto di bianco perch\u00e9 usavano luci a candela nell&#8217;era Edo quando il kabuki ebbe inizio. Tuttavia, questa tradizione viene mantenuta ancora oggi come un aspetto unico del kabuki in Giappone.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Palcoscenico<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il palcoscenico del kabuki \u00e8 unico e utilizza molteplici <strong>meccanismi scenici<\/strong> che consentono agli attori di apparire, scomparire e spuntare improvvisamente dall&#8217;alto del palco. Inoltre, dettagliati allestimenti scenici fatti a mano creano un&#8217;atmosfera eccezionale specifica per ogni spettacolo ed \u00e8 un piacere vedere le opere d&#8217;arte e gli oggetti realizzati da specialisti. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La differenza pi\u00f9 evidente tra il palcoscenico del kabuki e un palco normale \u00e8 che nel palco di uno spettacolo kabuki c&#8217;\u00e8 un percorso che collega il palcoscenico al retro del palco chiamato <em>hanamichi<\/em>, dove gli attori possono entrare ed uscire. Questo hanamichi collega gli attori al pubblico, facendo sentire attori e spettatori molto vicini, il che \u00e8 unico del teatro kabuki. A volte gli attori regalano piccoli oggetti che utilizzano nello spettacolo, come giornali, al pubblico seduto proprio accanto all&#8217;hanamichi!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Dove vedere il kabuki in Giappone<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In Giappone ci sono vari teatri che rappresentano spettacoli di kabuki. I principali sono i seguenti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il Teatro Kabukiza, che si trova a Higashiginza a Tokyo.<\/li>\n\n\n\n<li>Il Teatro Shinbashi Enbujo, che \u00e8 a breve distanza a piedi dal Teatro Kabukiza.<\/li>\n\n\n\n<li>Il Teatro Minamiza di Kyoto, nella citt\u00e0 di Kyoto.<\/li>\n\n\n\n<li>Il Teatro Shochikuza di Osaka, nella citt\u00e0 di Osaka.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ci sono anche altri teatri in tutto il Giappone, come il Teatro Hakataza a Fukuoka e il Teatro Misonoza a Nagoya. Inoltre, gli attori del Kabuki si esibiscono spesso in tourn\u00e9e in tutto il Giappone per portare il kabuki anche al di fuori delle grandi citt\u00e0. Quindi, vale la pena controllare se uno spettacolo si sta avvicinando alla tua zona!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"798\" height=\"436\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-display.jpg\" alt=\"Esposizione di biglietti e performance di kabuki in Giappone fuori dal teatro Kabukiza di Ginza, Tokyo.\" class=\"wp-image-110751\" style=\"aspect-ratio:1.8302752293577982;width:840px;height:auto\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-display.jpg 798w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-display-300x164.jpg 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/10\/kabukiza-display-768x420.jpg 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Come acquistare i biglietti per il Kabuki?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qui, ti spiegheremo come vedere uno spettacolo di kabuki in Giappone presso il teatro pi\u00f9 conveniente, il Teatro Kabukiza a Higashiginza, Tokyo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni giorno ci sono due parti di spettacoli al teatro, la matin\u00e9e e lo spettacolo serale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ciascuna parte dura circa quattro ore<\/strong>, con alcune pause intermedie. Il prezzo varia a seconda della categoria dei posti, ma oscilla tra 4,000 e 20,000 yen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi acquistare i biglietti online, chiamando la biglietteria o recandoti presso la biglietteria situata nel secondo seminterrato del teatro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se non puoi impegnarti in uno spettacolo di quattro ore, ecco una buona notizia!<\/strong> Al Teatro Kabukiza sono stati ripristinati i <strong>posti <em>makumi<\/em><\/strong>, che ti consentono di<strong> guardare un atto <\/strong>di uno spettacolo esteso a un prezzo pi\u00f9 basso, a partire da giugno 2023. Il prezzo dipende dalla durata dell&#8217;atto che stai guardando, ma di solito varia da 700 a 1,500 yen per atto. Puoi prenotare i biglietti online a partire dal mezzogiorno del giorno prima o ottenerli in loco presso il banco dei biglietti makumi il giorno in cui assisti allo spettacolo. Se decidi di sperimentare questa bellissima, tradizionale e storica forma d&#8217;arte mentre sei in Giappone, visita <a href=\"https:\/\/www.kabukiweb.net\/about\/ticket\/\" target=\"_blank\" rel=\"noopener\">questo sito web<\/a> per acquistare i biglietti!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Traduzioni disponibili?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Teatro Kabukiza offriva un&#8217;audio-guida in inglese che potevi noleggiare a un costo inferiore, ma \u00e8 stata sospesa. L&#8217;unica opzione che offrono ora \u00e8 l&#8217;acquisto del programma in giapponese con sinossi in inglese sul retro, che si pu\u00f2 acquistare dopo essere entrati nel teatro o cercando storie e informazioni online prima di assistere allo spettacolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Teatro Nazionale del Giappone, d&#8217;altra parte, offre una guida in cuffia in inglese ogni volta che mettono in scena il kabuki. Tuttavia, il teatro sar\u00e0 chiuso per ristrutturazione da ottobre 2023 all&#8217;autunno 2029.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Come discusso in precedenza, alcuni spettacoli come i balletti, sono facili da capire poich\u00e9 gli attori si concentrano sulla danza e non parlano, quindi sono ancora piacevoli da guardare senza conoscere il giapponese. Questi teatri stanno facendo del loro meglio per accogliere ospiti stranieri, quindi speriamo che ci saranno pi\u00f9 opzioni disponibili in futuro!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Come guardare il kabuki al di fuori del Giappone<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un servizio di streaming chiamato <strong>Kabuki On-Demand<\/strong> trasmette alcuni degli spettacoli di kabuki pi\u00f9 popolari. \u00c8 disponibile in dieci paesi e regioni a un prezzo inferiore. Se desideri sperimentare il kabuki a casa tua, consulta <a href=\"https:\/\/www.kabukiweb.net\/about\/kabuki-ondemand\/\" target=\"_blank\" rel=\"noopener\">questo link<\/a> per vedere cosa \u00e8 disponibile!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se sei interessato a immergerti di pi\u00f9 nella cultura tradizionale, perch\u00e9 non vivere e studiare in Giappone? <a href=\"https:\/\/gogonihon.com\/it\/\">Visita il nostro sito web<\/a> per ulteriori informazioni. O, se non puoi impegnarti per un periodo pi\u00f9 lungo, offriamo anche viaggi di studio brevi da 2 a 4 settimane, che combinano lezioni di lingua con divertenti attivit\u00e0 culturali, e avrai l&#8217;opportunit\u00e0 di assistere a qualche spettacolo di kabuki nel tempo libero. Leggi di pi\u00f9 al riguardo <a href=\"https:\/\/gogonihon.com\/it\/trips\/\">qui<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per saperne di pi\u00f9 sulla cultura, tradizioni e vita di tutti i giorni in Giappone, continua a leggere il <a href=\"https:\/\/gogonihon.com\/it\/blog\/\">blog di Go! Go! Nihon<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il teatro kabuki in Giappone \u00e8 una delle pi\u00f9 grandi espressioni artistiche, con una lunga e ricca storia che risale a oltre 400 anni fa. Nel corso della storia, il kabuki ha attraversato molte trasformazioni e riforme. Tuttavia, sostenuto da numerosi appassionati e dagli straordinari sforzi di attori e produttori che continuano a rappresentare spettacoli [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":110730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[425],"tags":[834,826],"class_list":["post-111157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-giapponese","tag-divertimento","tag-tradizione"],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts\/111157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/comments?post=111157"}],"version-history":[{"count":0,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/posts\/111157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/media\/110730"}],"wp:attachment":[{"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/media?parent=111157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/categories?post=111157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gogonihon.com\/it\/wp-json\/wp\/v2\/tags?post=111157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}