{"id":30648,"date":"2018-07-07T16:00:12","date_gmt":"2018-07-07T16:00:12","guid":{"rendered":"https:\/\/gogonihon.com\/?p=30648"},"modified":"2026-01-15T14:59:53","modified_gmt":"2026-01-15T05:59:53","slug":"le-bento-japonais-la-boite-a-repas-qui-revolutionne-le-quotidien","status":"publish","type":"post","link":"https:\/\/gogonihon.com\/fr\/blog\/le-bento-japonais-la-boite-a-repas-qui-revolutionne-le-quotidien\/","title":{"rendered":"Le bento japonais, la bo\u00eete \u00e0 repas qui r\u00e9volutionne le quotidien"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La bo\u00eete \u00e0 <em>bento<\/em> fait partie de ces petites choses \u00e0 adopter de toute urgence quand <a href=\"https:\/\/gogonihon.com\/fr\/blog\/sinstaller-au-japon-petites-choses-a-savoir\/\">on emm\u00e9nage au Japon<\/a>. Pratique et facile \u00e0 pr\u00e9parer, elle est id\u00e9ale pour un d\u00e9jeuner sur le pouce et fait partie int\u00e9grante de la culture japonaise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que ce soit au bureau ou \u00e0 l\u2019\u00e9cole, dans le train ou lors d\u2019un pique-nique, les Japonais utilisent cette petite bo\u00eete au quotidien. Que renferme-t-elle? O\u00f9 se la procurer? Et comment la pr\u00e9senter? On d\u00e9couvre tout de suite l\u2019univers gourmand du <strong>bento japonaise<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u2019est ce qu\u2019un bento?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le bento (\u5f01\u5f53) d\u00e9signe traditionnellement <strong>la bo\u00eete \u00e0 repas japonaise<\/strong>. Tr\u00e8s proche en apparence de nos fameux tupperwares, le bento japonais est en r\u00e9alit\u00e9 bien plus qu\u2019une simple bo\u00eete: c\u2019est une tradition \u00e0 part enti\u00e8re!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apparu au Ve si\u00e8cle, le bento prend l\u2019apparence d\u2019une petite bo\u00eete en bambou dans laquelle on met du riz pour le d\u00e9jeuner. Utilis\u00e9 par toutes les classes sociales de l\u2019\u00e9poque, le bento devient rapidement indissociable du quotidien japonais. Et on l\u2019utilise aussi bien au travail que sur les champs de bataille au moment des pauses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien qu\u2019elle ne soit plus en bambou aujourd\u2019hui, la boite \u00e0 bento reste tr\u00e8s populaire au Japon. Qu\u2019elle soit en plastique, ou en inox, \u00e0 compartiments, ou \u00e0 niveaux, elle s\u2019adapte aux besoins de chacun et permet de transporter avec soi les aliments sans qu\u2019ils se m\u00e9langent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, contrairement au repas fran\u00e7ais o\u00f9 le plat principal est g\u00e9n\u00e9ralement consistant, au Japon, le repas se compose de plusieurs petites portions. Bien plus \u00e9quilibr\u00e9 qu\u2019un sandwich, le bento est donc un bon moyen de retranscrire ses habitudes alimentaires en dehors de la maison.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"898\" height=\"491\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/colorful-bento-box.png\" alt=\"Bento japonais compos\u00e9 de plusieurs petits plats color\u00e9s\" class=\"wp-image-206111\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/colorful-bento-box.png 898w, https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/colorful-bento-box-300x164.png 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/colorful-bento-box-768x420.png 768w\" sizes=\"(max-width: 898px) 100vw, 898px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">O\u00f9 en acheter?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous cuisinez, vous serez s\u00fbrement int\u00e9ress\u00e9 par la bo\u00eete en elle-m\u00eame. On en trouve g\u00e9n\u00e9ralement dans les <a href=\"https:\/\/gogonihon.com\/fr\/blog\/les-magasins-a-100-yens\/\">100 yens shops<\/a>, ou dans les magasins de d\u00e9coration comme Loft et Nitori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A contrario, si vous n\u2019avez pas le temps de cuisiner, la bo\u00eete \u00e0 bento toute pr\u00e9par\u00e9e peut \u00eatre une solution int\u00e9ressante. Vendus \u00e0 petits prix dans les <a href=\"https:\/\/gogonihon.com\/fr\/blog\/konbini-japonais-magasins-a-tout-faire\/\"><em>konbini<\/em><\/a> et les supermarch\u00e9s, les bento sont \u00e9galement pr\u00e9sents dans les gares pour permettre aux voyageurs de se sustenter lors de leurs d\u00e9placements en train. Ces derniers sont d\u2019ailleurs tr\u00e8s populaires sur l\u2019archipel et ont m\u00eame leur propre nom, <strong><em>Ekiben<\/em><\/strong> (\u99c5\u5f01), issu de la fusion des mots gare (<em>eki<\/em>) et bento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 noter \u00e9galement que certains restaurants proposent des bento de leurs meilleurs produits, et que des traiteurs sp\u00e9cialis\u00e9s dans les lunch box existent dans de nombreux quartiers.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u2019y a -t-il dans une bo\u00eete \u00e0 repas japonaise?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bien qu\u2019on puisse mettre tout ce qu\u2019on d\u00e9sire dans sa bo\u00eete \u00e0 repas, le bento japonais reste principalement constitu\u00e9 de <a href=\"https:\/\/gogonihon.com\/fr\/blog\/le-riz-au-japon-bien-plus-qu-un-simple-aliment\/\">riz<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e9vu pour respecter les apports alimentaires journaliers recommand\u00e9s par les nutritionnistes, le bento se compose g\u00e9n\u00e9ralement \u00e0 40 % de f\u00e9culents, \u00e0 30 % de prot\u00e9ines, et \u00e0 20 % de l\u00e9gumes.<br>Parmi <strong>les aliments<\/strong> que vous retrouverez fr\u00e9quemment dans ces petites bo\u00eetes, on aura alors:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>du poisson ou une viande sous forme de boulettes ou de <em><a href=\"https:\/\/gogonihon.com\/fr\/blog\/le-katsu-japonais\/\">katsu<\/a>,<\/em> pour que cela soit facile \u00e0 manger.<\/li>\n\n\n\n<li>un \u0153uf au plat dit <em>Tamagoyaki<\/em> ou une omelette.<\/li>\n\n\n\n<li>des l\u00e9gumes froids comme des b\u00e2tonnets de carottes, des petites tomates, ou des pousses de soja.<\/li>\n\n\n\n<li>une salade de p\u00e2tes ou de pommes de terre \u00e0 la mayonnaise.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Si votre bo\u00eete \u00e0 bento se compose de plusieurs \u00e9tages, vous pouvez \u00e9galement mettre quelques fruits de saison dans l\u2019un des compartiments.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"898\" height=\"491\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/train-bento-box.png\" alt=\"Bento japonais au b\u0153uf d\u00e9gust\u00e9 dans un train au Japon\" class=\"wp-image-206120\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/train-bento-box.png 898w, https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/train-bento-box-300x164.png 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2018\/07\/train-bento-box-768x420.png 768w\" sizes=\"(max-width: 898px) 100vw, 898px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Comment pr\u00e9senter son bento?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La pr\u00e9paration du bento japonais, c\u2019est tout un art! De l\u2019emballage aux ingr\u00e9dients, le bento doit \u00eatre aussi all\u00e9chant pour les papilles que pour les yeux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est pourquoi il n\u2019y a pas vraiment de r\u00e8gles lorsqu\u2019il s\u2019agit de pr\u00e9senter sa bo\u00eete \u00e0 repas. Qu\u2019elles soient sobres, color\u00e9es, ou orn\u00e9es de petits dessins, la bo\u00eete \u00e0 bento doit avant tout \u00eatre au go\u00fbt de celui qui l\u2019utilise.<br>La taille des bo\u00eetes varie selon l\u2019app\u00e9tit de chacun, les baguettes sont choisies avec soin pour ne pas d\u00e9noter avec la lunch box, et le sac qui transporte la bo\u00eete est g\u00e9n\u00e9ralement assorti avec le tout.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour ce qui est du sac, ce dernier est souvent rigide, mais peut \u00e9galement prendre l\u2019apparence d\u2019un simple tissu. Appel\u00e9es <strong><em>Furoshiki<\/em><\/strong> (\u98a8\u5442\u6577), ces \u00e9toffes \u00e9taient autrefois utilis\u00e9es pour emballer les bento et les pr\u00e9sents \u00e0 offrir. Bien que le sac repas accompagne d\u00e9sormais la plupart des bento, les Furoshiki sont encore tr\u00e8s appr\u00e9ci\u00e9s des Japonais qui veulent donner un style authentique \u00e0 leur bo\u00eete \u00e0 repas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Particuli\u00e8rement soign\u00e9e \u00e0 l\u2019ext\u00e9rieur, l\u2019esth\u00e9tisme du bento se poursuit parfois jusqu\u2019au c\u0153ur de la bo\u00eete. Riz en forme de petits personnages mignons et disposition des l\u00e9gumes millim\u00e9tr\u00e9e, certains bentos ressemblent \u00e0 de v\u00e9ritables \u0153uvres d\u2019art! Notamment, les bento des \u00e9coliers, que les m\u00e8res de famille ont pris soin de rendre les plus app\u00e9tissants possibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien plus qu\u2019une simple bo\u00eete \u00e0 repas, le bento japonais est donc un moyen de laisser parler son sens cr\u00e9atif et d\u2019affirmer ses go\u00fbts avec une bo\u00eete qui correspond \u00e0 la personnalit\u00e9 de chacun.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et vous, \u00e0 quoi ressemble le v\u00f4tre?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour en conna\u00eetre plus sur le Japon, suivez les derni\u00e8res publication du <a href=\"https:\/\/gogonihon.com\/fr\/blog\/\">blog de Go! Go! Nihon<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La bo\u00eete \u00e0 bento fait partie de ces petites choses \u00e0 adopter de toute urgence quand on emm\u00e9nage au Japon. Pratique et facile \u00e0 pr\u00e9parer, elle est id\u00e9ale pour un d\u00e9jeuner sur le pouce et fait partie int\u00e9grante de la culture japonaise. Que ce soit au bureau ou \u00e0 l\u2019\u00e9cole, dans le train ou lors [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":29185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[408],"tags":[754,739,740],"class_list":["post-30648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuisine-japonaise","tag-nourriture","tag-style","tag-tradition"],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/posts\/30648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/comments?post=30648"}],"version-history":[{"count":0,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/posts\/30648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/media\/29185"}],"wp:attachment":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/media?parent=30648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/categories?post=30648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/tags?post=30648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}