{"id":30212,"date":"2023-09-07T06:00:00","date_gmt":"2023-09-07T06:00:00","guid":{"rendered":"https:\/\/gogonihon.com\/?p=30212"},"modified":"2023-09-07T01:39:43","modified_gmt":"2023-09-07T01:39:43","slug":"comment-prendre-un-rendez-vous-en-japonais","status":"publish","type":"post","link":"https:\/\/gogonihon.com\/fr\/blog\/comment-prendre-un-rendez-vous-en-japonais\/","title":{"rendered":"Comment prendre un rendez-vous en japonais"},"content":{"rendered":"\n<p>Qu&rsquo;il s&rsquo;agisse d&rsquo;appeler votre coiffeur ou le dentiste pour un d\u00e9tartrage, vous aurez probablement besoin de prendre un rendez-vous en japonais au moins quelques fois pendant votre s\u00e9jour au Japon.<\/p>\n\n\n\n<p>Parler au t\u00e9l\u00e9phone dans une langue \u00e9trang\u00e8re peut \u00eatre tr\u00e8s stressant, surtout si vous ne vous sentez pas \u00e0 l&rsquo;aise avec cette langue. Nous sommes l\u00e0 pour vous aider \u00e0 trouver les mots et les expressions en japonais dont vous avez besoin pour prendre un rendez-vous.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les bases<\/strong><\/h2>\n\n\n\n<p>Le mot pour \u00ab\u00a0r\u00e9servation\u00a0\u00bb ou \u00ab\u00a0rendez-vous\u00a0\u00bb en japonais est <strong><em>yoyaku<\/em><\/strong>, \u4e88\u7d04 et \u00ab\u00a0pour faire une r\u00e9servation\/un rendez-vous\u00a0\u00bb est <em><strong>yoyaku o suru<\/strong><\/em>, \u4e88\u7d04\u3092\u3059\u308b.<\/p>\n\n\n\n<p>Lorsque vous appelez pour faire une r\u00e9servation, la phrase \u00e0 dire apr\u00e8s le salutation initiale est :<\/p>\n\n\n\n<p><em><strong>Yoyaku o onegai shitain desu ga.<\/strong><\/em><br>\u4e88\u7d04\u3092\u304a\u9858\u3044\u3057\u305f\u3044\u3093\u3067\u3059\u304c\u3002<br>Je souhaite faire une r\u00e9servation<\/p>\n\n\n\n<p>La combinaison \u00ab\u00a0-n desu ga\u00a0\u00bb est utilis\u00e9e pour att\u00e9nuer une demande car autrement, celle-ci semble brutale, ou irespectueuse.<\/p>\n\n\n\n<p>On peut aussi dire :<\/p>\n\n\n\n<p><em><strong>Yoyaku shitain desu ga.<\/strong><\/em><br>\u4e88\u7d04\u3057\u305f\u3044\u3093\u3067\u3059\u304c\u3002<\/p>\n\n\n\n<p>Ou<\/p>\n\n\n\n<p><strong><em>Yoyaku onegaishimasu.<\/em><\/strong><br>\u4e88\u7d04\u304a\u9858\u3044\u3057\u307e\u3059\u3002<\/p>\n\n\n\n<p>Cependant, nous pourrions recommander de s&rsquo;en tenir \u00e0 la premi\u00e8re phrase pour \u00eatre le plus poli possible.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/08\/university-hospital-sign-in-Japan.jpg\" alt=\"Panneau d'entr\u00e9e de l'h\u00f4pital universitaire Tokai \u00e0 Tokyo.\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Exemple : r\u00e9servation chez le dentiste<\/strong><\/h2>\n\n\n\n<p>Il ne s&rsquo;agit que d&rsquo;un guide de base sur la mani\u00e8re de faire une r\u00e9servation chez le dentiste. Lorsque vous prenez un rendez-vous en japonais en r\u00e9alit\u00e9, vous devez \u00e9couter attentivement ce que dit l&rsquo;autre personne et lui r\u00e9pondre de mani\u00e8re appropri\u00e9e. En outre, il se peut que les interlocuteurs utilisent diff\u00e9rents niveaux de politesse, alors soyez \u00e9galement attentif \u00e0 votre fa\u00e7on d&rsquo;utiliser le vocabulaire.<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><b><i>\u201cHai, Go! Go! Nihon Shika-inn desu.\u201d<br><\/i><\/b>\u306f\u3044\u3001\u30b4\u30b4\u30cb\u30db\u30f3\u6b6f\u79d1\u533b\u9662\u3067\u3059\u3002<br>Bonjour, c&rsquo;est la clinique dentaire Go ! Go ! Nihon.<\/p>\n\n\n\n<p>Vous :<br><strong><em>\u00ab\u00a0Moshi moshi\u00a0\u00bb. Sumimasen, yoyaku o onegai shitain desu ga.\u00a0\u00bb<\/em><\/strong><br>\u3082\u3057\u3082\u3057\u3002\u3059\u307f\u307e\u305b\u3093\u3001\u4e88\u7d04\u3092\u304a\u9858\u3044\u3057\u305f\u3044\u3093\u3067\u3059\u304c\u3002<br>Bonjour, je voudrais faire une r\u00e9servation, s&rsquo;il vous pla\u00eet.<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><em><strong>\u00ab\u00a0Hai\u00a0\u00bb<\/strong><\/em><br>\u306f\u3044<br>Bien s\u00fbr.<\/p>\n\n\n\n<p>Vous :<br><b><i>\u201cKiny\u014dbi oneigashimasu.\u201d<br><\/i><\/b>\u91d1\u66dc\u65e5\u304a\u9858\u3044\u3057\u307e\u3059\u3002<br>Vendredi s&rsquo;il vous pla\u00eet.<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><em><strong>\u00ab\u00a0Nanji kara ga yoroshii desuka ?\u00a0\u00bb<\/strong><\/em><br>\u4f55\u6642\u304b\u3089\u304c\u3088\u308d\u3057\u3044\u3067\u3059\u304b\uff1f<br>\u00c0 partir de quelle heure cela vous convient-il ?<\/p>\n\n\n\n<p>Vous :<br><em><strong>\u00ab\u00a0Rokuji han kara onegaishimasu\u00a0\u00bb<\/strong><\/em><br>\uff16\u6642\u534a\u304b\u3089\u304a\u9858\u3044\u3057\u307e\u3059\u3002<br>A partir de 18h30 s&rsquo;il vous pla\u00eet.<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><em><strong>\u00ab\u00a0Hai, onamae wa nan deshouka ?\u00a0\u00bb<\/strong><\/em><br>\u306f\u3044\u3001\u304a\u540d\u524d\u306f\u4f55\u3067\u3057\u3087\u3046\u304b\uff1f<br>Certainement, quel est votre nom ?<\/p>\n\n\n\n<p>Vous :<br><em><strong>\u00ab\u00a0Anna desu\u00a0\u00bb.<\/strong><\/em><br>\u30a2\u30f3\u30ca\u3067\u3059\u3002<br>C&rsquo;est Anna.<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><em><strong>\u00ab\u00a0Odenwabango o onegaishimasu.\u00a0\u00bb<\/strong><\/em><br>\u304a\u96fb\u8a71\u756a\u3092\u304a\u9858\u3044\u3057\u307e\u3059\u3002<br>Votre num\u00e9ro de t\u00e9l\u00e9phone, s&rsquo;il vous pla\u00eet.<\/p>\n\n\n\n<p>Vous :<br><em><strong>\u00ab\u00a0Ichi-ni-san-no-yon-go-roku-no-nana-hachi-ky\u016b\u00a0\u00bb<\/strong><\/em><br>123\u306e456\u306e789<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><b><i>\u201cHai, goyoyaku no kakunin o itashimasu. Kiny\u014dbi no rokuji han kara Anna-sama desu.\u201d<br><\/i><\/b>\u306f\u3044\u3001\u3054\u4e88\u7d04\u306e\u78ba\u8a8d\u3092\u3044\u305f\u3057\u307e\u3059\u3002\u91d1\u66dc\u65e5\u306e\uff16\u6642\u534a\u304b\u3089\u30a2\u30f3\u30ca\u69d8\u3067\u3059\u3002<br>Bien s\u00fbr, je vais r\u00e9p\u00e9ter votre r\u00e9servation. Anna, vendredi soir \u00e0 18h.<\/p>\n\n\n\n<p>Vous :<br><em><strong>\u00ab\u00a0Hai, yoroshiku onegaishimasu.\u00a0\u00bb<\/strong><\/em><br>\u306f\u3044\u3001\u3088\u308d\u3057\u304f\u304a\u9858\u3044\u3057\u307e\u3059\u3002<br>Oui, merci beaucoup.<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><em><strong>\u00ab\u00a0Omachi shite orimasu\u00a0\u00bb. Arigat\u014dgozaimasu.\u00a0\u00bb<\/strong><\/em><br>\u304a\u5f85\u3061\u3057\u3066\u304a\u308a\u307e\u3059\u3002\u3042\u308a\u304c\u3068\u3046\u3054\u3056\u3044\u307e\u3059\u3002<br>Nous vous attendons. Merci beaucoup.<\/p>\n\n\n\n<p>Vous pouvez \u00e9galement rencontrer une situation o\u00f9 le cabinet ne peut pas prendre en compte votre r\u00e9servation pour le jour et\/ou l&rsquo;heure de votre choix. Voici comment cette conversation pourrait se d\u00e9rouler :<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><em><strong>\u00ab\u00a0Sumimasen, kiny\u014dbi no yoru wa yoyaku ga ippai desu. Hoka no hi wa ikaga desuka ?<\/strong><\/em><br>\u3059\u307f\u307e\u305b\u3093\u3001\u91d1\u66dc\u65e5\u306e\u3088\u308b\u306f\u4e88\u7d04\u304c\u3044\u3063\u3071\u3044\u3067\u3059\u3002\u4ed6\u306e\u65e5\u306f\u3044\u304b\u304c\u3067\u3059\u304b\uff1f<br>Je suis d\u00e9sol\u00e9, les r\u00e9servations pour vendredi soir sont compl\u00e8tes. Pourquoi pas un autre jour ?<\/p>\n\n\n\n<p>Vous :<br><em><strong>\u00ab\u00a0S\u014ddesuka, ja, nichiy\u014dbi wa d\u014d desuka ?<\/strong><\/em><br>\u305d\u3046\u3067\u3059\u304b\u3001\u3058\u3083\u3001\u65e5\u66dc\u65e5\u306f\u3069\u3046\u3067\u3059\u304b\uff1f<br>Oh. Et dimanche ?<\/p>\n\n\n\n<p>Le cabinet dentaire :<br><em><strong>\u00ab\u00a0Hai, kekk\u014d desu.\u00a0\u00bb<\/strong><\/em><br>\u306f\u3044\u3001\u7d50\u69cb\u3067\u3059\u3002<br>Oui, c&rsquo;est possible.<\/p>\n\n\n\n<p>Si, \u00e0 un moment donn\u00e9, vous ne comprenez pas l&rsquo;autre personne, vous pouvez lui demander de r\u00e9p\u00e9ter ce qu&rsquo;elle a dit.<\/p>\n\n\n\n<p><em><strong>\u00ab\u00a0Sumimasen, m\u014d ichido itte moraemasenka ?\u00a0\u00bb<\/strong><\/em><br>\u3059\u307f\u307e\u305b\u3093\u3001\u3082\u3046\u4e00\u5ea6\u8a00\u3063\u3066\u3082\u3089\u3048\u307e\u305b\u3093\u304b\uff1f<br>D\u00e9sol\u00e9, pourriez-vous r\u00e9p\u00e9ter cela pour moi ?<\/p>\n\n\n\n<p>Pour d&rsquo;autres mots et expressions que vous pouvez utiliser chez le dentiste ou dans une clinique, lisez <a href=\"https:\/\/gogonihon.com\/fr\/blog\/vocabulaire-et-phrases-utiles-lorsque-vous-etes-malade-au-japon\/\">notre article<\/a>. Si vous avez besoin d&rsquo;aide avec une maladie sp\u00e9cifique ou avez besoin de soutien, renseignez-vous sur <a href=\"https:\/\/japanhealthinfo.com\/emergency-services\/emergency-clinics-and-hospitals\/\" target=\"_blank\" rel=\"noopener\">Japan Healthcare Info<\/a>, ou contactez un service similaire.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"798\" height=\"436\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/09\/man-making-a-call.jpg\" alt=\"Une personne, vue de dos, commence \u00e0 prendre un rendez-vous en japonais par t\u00e9l\u00e9phone.\" class=\"wp-image-108505\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/09\/man-making-a-call.jpg 798w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/09\/man-making-a-call-300x164.jpg 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/09\/man-making-a-call-768x420.jpg 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Prendre d&rsquo;autres types de rendez-vous<\/strong><\/h2>\n\n\n\n<p>Quelle que soit la raison de votre r\u00e9servation, le vocabulaire et les phrases de base pour prendre un rendez-vous en japonais restent plus ou moins les m\u00eames. Il se peut que l&rsquo;on vous pose des questions sp\u00e9cifiques en fonction du type de rendez-vous que vous prenez et nous vous recommandons d&rsquo;\u00e9tudier un certain vocabulaire afin que vous soyez pr\u00eat.<\/p>\n\n\n\n<p>Par exemple, lorsque vous appelez un coiffeur, il se peut qu&rsquo;on vous pose des questions :<br><strong><em>\u00ab\u00a0Gokib\u014dno s\u0101bisu wa nan deshouka ?\u00a0\u00bb<\/em><\/strong><br>\u3054\u5e0c\u671b\u306e\u30b5\u30fc\u30d3\u30b9\u306f\u306a\u3093\u3067\u3057\u3087\u3046\u304b ?<br>Quel service souhaitez-vous ?<\/p>\n\n\n\n<p>Il serait utile de conna\u00eetre des mots de base comme<em><strong> torimingu<\/strong><\/em> \u30c8\u30ea\u30df\u30f3\u30b0 (coupe)<em>,<\/em><em><strong> katto<\/strong><\/em>\u30ab\u30c3\u30c8 (coupe de cheveux) et <strong><em>hairaito<\/em> <\/strong>\u30cf\u30a4\u30e9\u30a4\u30c8 (m\u00e8ches).<\/p>\n\n\n\n<p>Si vous avez un coiffeur pr\u00e9cis avec lequel vous aimeriez r\u00e9server, vous pouvez dire :<\/p>\n\n\n\n<p><em><strong>\u00ab\u00a0Tanaka-san de onegaishimasu\u00a0\u00bb.<\/strong><\/em><br>\u7530\u4e2d\u3055\u3093\u3067\u304a\u9858\u3044\u3057\u307e\u3059\u3002<br>Tanaka-san, s&rsquo;il vous pla\u00eet.<\/p>\n\n\n\n<p>Ou si vous \u00eates d\u00e9j\u00e0 au salon et que vous souhaitez prendre un autre rendez-vous avec un coiffeur en particulier, vous pouvez dire :<br><em><strong>\u00ab\u00a0Tsugi mo Tanakasan de onegaishimasu.\u00a0\u00bb<\/strong><\/em><br>\u6b21\u3082\u7530\u4e2d\u3055\u3093\u3067\u304a\u9858\u3044\u3057\u307e\u3059\u3002<br>La prochaine fois, la m\u00eame personne s&rsquo;il vous pla\u00eet.<\/p>\n\n\n\n<p>De m\u00eame, si vous prenez un rendez-vous chez le m\u00e9decin, il serait utile de conna\u00eetre un certain vocabulaire. <a href=\"https:\/\/gogonihon.com\/fr\/blog\/vocabulaire-et-phrases-utiles-lorsque-vous-etes-malade-au-japon\/\">Lisez notre article<\/a> sur le vocabulaire et les expressions \u00e0 utiliser lorsque vous \u00eates malade au Japon.<\/p>\n\n\n\n<p>N&rsquo;oubliez pas que la prise de rendez-vous est une conversation \u00e0 deux sens et, m\u00eame si cela peut sembler effrayant la premi\u00e8re fois, il est pr\u00e9f\u00e9rable de ne pas avoir un dialogue d\u00e9j\u00e0 pr\u00e9par\u00e9 dans votre t\u00eate. Passez plut\u00f4t un appel en sachant quelles sont les informations essentielles et comment les communiquer en japonais, et faites de votre mieux pour \u00e9couter attentivement ce que dit l&rsquo;autre personne. Vous y arriverez une fois que vous l&rsquo;aurez fait plusieurs fois et que vos comp\u00e9tences linguistiques se seront am\u00e9lior\u00e9es !<\/p>\n\n\n\n<p>Vous souhaitez apprendre davantage le japonais ? Pourquoi ne pas vous inscrire \u00e0 notre programme en ligne de 12 semaines de cours de japonais pour d\u00e9butants, dispens\u00e9 par Akamonkai, l&rsquo;une des plus grandes \u00e9coles de langues de Tokyo. Pour en savoir plus sur ce cours, <a href=\"https:\/\/japaneseonline.gogonihon.com\/courses\/akamonkai-japanese-12-week-beginner-course\">cliquez ici<\/a>.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/gogonihon.com\/fr\/blog\/category\/apprendre-le-japonais\/\">Pour en savoir plus<\/a> sur la langue japonaise, consultez notre blog !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;il s&rsquo;agisse d&rsquo;appeler votre coiffeur ou le dentiste pour un d\u00e9tartrage, vous aurez probablement besoin de prendre un rendez-vous en japonais au moins quelques fois pendant votre s\u00e9jour au Japon. Parler au t\u00e9l\u00e9phone dans une langue \u00e9trang\u00e8re peut \u00eatre tr\u00e8s stressant, surtout si vous ne vous sentez pas \u00e0 l&rsquo;aise avec cette langue. Nous sommes [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":30214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[407],"tags":[753],"class_list":["post-30212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils-pratiques","tag-langue"],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/posts\/30212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/comments?post=30212"}],"version-history":[{"count":0,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/posts\/30212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/media\/30214"}],"wp:attachment":[{"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/media?parent=30212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/categories?post=30212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gogonihon.com\/fr\/wp-json\/wp\/v2\/tags?post=30212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}