{"id":891,"count":143,"description":"","link":"https:\/\/gogonihon.com\/es\/blog\/tag\/estudiar-en-japon\/","name":"estudiar en Jap\u00f3n","slug":"estudiar-en-japon","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/tags\/891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/posts?tags=891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}