{"id":101011,"date":"2023-07-19T06:00:00","date_gmt":"2023-07-19T06:00:00","guid":{"rendered":"https:\/\/gogonihon.com\/?p=101011"},"modified":"2026-04-30T14:07:26","modified_gmt":"2026-04-30T05:07:26","slug":"aprobar-el-jlpt-n5","status":"publish","type":"post","link":"https:\/\/gogonihon.com\/es\/blog\/aprobar-el-jlpt-n5\/","title":{"rendered":"Aprobar el JLPT N5: todo lo que necesitas saber"},"content":{"rendered":"\n<p>Si est\u00e1s aprendiendo japon\u00e9s, probablemente hayas o\u00eddo hablar del <strong>Japanese Language Proficiency Test <\/strong>(JLPT o NOKEN). En esta serie de cinco partes, desglosaremos cada nivel de este examen, veremos de qu\u00e9 te evaluar\u00e1n, c\u00f3mo te calificar\u00e1n y c\u00f3mo puedes prepararte para este examen. En este primer art\u00edculo analizaremos el JLPT N5.<\/p>\n\n\n\n<p>\u00a1Sigue leyendo para saber m\u00e1s sobre c\u00f3mo aprobar el examen JLPT N5!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Una introducci\u00f3n al JLPT<\/strong><\/h2>\n\n\n\n<p>El JLPT existe desde 1984 y actualmente es el examen de idioma japon\u00e9s m\u00e1s realizado en el mundo.<\/p>\n\n\n\n<p>Adem\u00e1s de actuar como un indicador de la capacidad ling\u00fc\u00edstica para los empleadores japoneses que contratan trabajadores extranjeros, aprobar un examen JLPT tambi\u00e9n sirve para cumplir con el <a href=\"https:\/\/gogonihon.com\/es\/blog\/que-ha-pasado-con-el-requisito-de-150-horas\/\">requisito del gobierno de realizar 150 horas de estudio<\/a>.<\/p>\n\n\n\n<p>Hay <strong>cinco niveles<\/strong> del JLPT, siendo el N5 el nivel m\u00e1s f\u00e1cil de aprobar y el N1 el m\u00e1s dif\u00edcil. No tienes que aprobar un cierto nivel antes de pasar al siguiente nivel, es decir, no tienes que haber aprobado N5 antes de poder realizar el examen N4.<\/p>\n\n\n\n<p>Cada examen eval\u00faa cuatro cosas: comprensi\u00f3n lectora, gram\u00e1tica, vocabulario y comprensi\u00f3n auditiva.<\/p>\n\n\n\n<p>En Jap\u00f3n, el examen se realiza normalmente dos veces al a\u00f1o, una en julio y otra en diciembre. Te puedes presentar al examen en muchos otros pa\u00edses, pero no en todos los lugares puedes realizarlo dos veces al a\u00f1o.<\/p>\n\n\n\n<p>En la <a href=\"https:\/\/www.jlpt.jp\/e\/application\/overseas_list.html\" target=\"_blank\" rel=\"noopener\">pagina web oficial del JLPT<\/a> encontrar\u00e1s la informaci\u00f3n m\u00e1s actualizada sobre d\u00f3nde y cu\u00e1ndo puedes presentarte al examen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfPor qu\u00e9 presentarse al examen JLPT N5?<\/strong><\/h2>\n\n\n\n<p>Prepararse y presentarse al examen JLPT N5 es una <strong>excelente experiencia de aprendizaje<\/strong> y un <strong>motivador<\/strong> para los estudiantes principiantes de japon\u00e9s. Empezar a aprender un nuevo idioma puede ser todo un desaf\u00edo, y ponerte como objetivo aprobar un examen puede darte una estructura de trabajo y crear objetivos de aprendizaje que te ayuden a llevar tus habilidades ling\u00fc\u00edsticas al siguiente nivel.<\/p>\n\n\n\n<p>Aprobar el N5 no te abrir\u00e1 las puertas para encontrar un trabajo en una empresa japonesa, pero demuestra tu <strong>capacidad para comprender los componentes b\u00e1sicos del idioma<\/strong>. Esta base es crucial para el futuro \u00e9xito en tu aprendizaje del idioma japon\u00e9s.<\/p>\n\n\n\n<p>Tampoco minimicemos la sensaci\u00f3n de logro que sentir\u00e1s cuando apruebes el examen. Puede que estudiar japon\u00e9s sea tu sue\u00f1o de toda la vida, o que tengas herencia japonesa y quieras conectarte con tus ra\u00edces. Sea cual sea el motivo por el que has empezado a estudiar japon\u00e9s, aprobar tu primer examen JLPT ser\u00e1 un <strong>hito importante<\/strong> que no debes minusvalorar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"798\" height=\"436\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-29.png\" alt=\"Imagen de un libro JLPT N5 sobre un escritorio en una clase\" class=\"wp-image-187734\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-29.png 798w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-29-300x164.png 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-29-768x420.png 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfDe qu\u00e9 se te eval\u00faa en el examen JLPT N5?<\/strong><\/h2>\n\n\n\n<p>El N5 pone a prueba tu capacidad para comprender algo de japon\u00e9s b\u00e1sico. Eso quiere decir que ser\u00e1s capaz de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Leer hiragana y katakana&nbsp;<\/li>\n\n\n\n<li>Conocer unos 100 kanji &#8211; estos ser\u00e1n los kanji m\u00e1s fundamentales y comunes, que normalmente estudiar\u00e1s como estudiante principiante de japon\u00e9s<\/li>\n\n\n\n<li>Identificar vocabulario &#8211; unas 800 palabras diferentes<\/li>\n<\/ul>\n\n\n\n<p>Debes poder leer y comprender expresiones y oraciones t\u00edpicas escritas en hiragana, katakana y kanjis b\u00e1sicos. Tambi\u00e9n debes poder escuchar y comprender conversaciones sobre la vida cotidiana y situaciones dentro de clase, y poder captar la informaci\u00f3n necesaria de conversaciones breves habladas lentamente.<\/p>\n\n\n\n<p>Cubrir\u00e1s todo esto en nuestro <a href=\"https:\/\/japaneseonline.gogonihon.com\/courses\/akamonkai-japanese-12-week-beginner-course\">curso de japon\u00e9s online para principiantes de Akamonkai<\/a>, el cual te preparar\u00e1 para el JLPT N5 en tan solo 12 semanas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Estructura del examen<\/strong><\/h2>\n\n\n\n<p>El examen tiene tres secciones y cada una tiene un tiempo l\u00edmite para ser completada.<\/p>\n\n\n\n<p><strong>Vocabulario <\/strong>(20 minutos)<\/p>\n\n\n\n<p>En la secci\u00f3n de vocabulario, se te evaluar\u00e1 en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lectura de palabras en kanji<\/li>\n\n\n\n<li>Kanji y katakana de palabras escritas en hiragana<\/li>\n\n\n\n<li>El significado de las palabras definidas por el contexto<\/li>\n\n\n\n<li>Palabras y expresiones con significados similares<\/li>\n<\/ul>\n\n\n\n<p><strong>Gram\u00e1tica y lectura<\/strong> (40 minutos)<\/p>\n\n\n\n<p>En la secci\u00f3n de gram\u00e1tica y lectura, se te evaluar\u00e1 en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elegir el formato gramatical que mejor se adapte a la oraci\u00f3n<\/li>\n\n\n\n<li>Composici\u00f3n precisa de oraciones<\/li>\n\n\n\n<li>Idoneidad de las oraciones para el contexto del escrito<\/li>\n\n\n\n<li>Comprensi\u00f3n de textos sencillos de unos 80 caracteres sobre temas y situaciones relacionadas con el estudio, la vida cotidiana y el trabajo<\/li>\n\n\n\n<li>Comprensi\u00f3n de un texto f\u00e1cil de unos 250 caracteres sobre temas de la vida cotidiana<\/li>\n\n\n\n<li>Capacidad para captar informaci\u00f3n de materiales, como anuncios y avisos de unas 250 palabras<\/li>\n<\/ul>\n\n\n\n<p><strong>Comprensi\u00f3n auditiva<\/strong> (30 minutos)<\/p>\n\n\n\n<p>Se te evaluar\u00e1 en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Capacidad para comprender la informaci\u00f3n necesaria para resolver problemas espec\u00edficos y comprender la acci\u00f3n apropiada a tomar.<\/li>\n\n\n\n<li>Capacidad para resumir en funci\u00f3n de la informaci\u00f3n necesaria presentada con antelaci\u00f3n<\/li>\n\n\n\n<li>Habilidad para elegir expresiones verbales apropiadas escuchando y mirando ilustraciones<\/li>\n\n\n\n<li>Capacidad para elegir las respuestas correctas escuchando frases cortas, como preguntas<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Puntuaci\u00f3n del examen<\/strong><\/h2>\n\n\n\n<p>Para aprobar el examen JLPT, necesitas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Tu puntuaci\u00f3n total debe ser igual o superior a los puntos generales requeridos para aprobar (\u00abel corte general de aprobaci\u00f3n\u00bb)<\/li>\n\n\n\n<li>Tu puntuaci\u00f3n en cada secci\u00f3n debe ser igual o superior a los puntos requeridos para aprobar cada secci\u00f3n (\u00abel corte de aprobaci\u00f3n de la secci\u00f3n\u00bb)<\/li>\n<\/ol>\n\n\n\n<p>Si hay alguna secci\u00f3n que no logres superar, suspender\u00e1s el examen, incluso si has alcanzado el total de puntos necesarios para aprobar.<\/p>\n\n\n\n<p>Para el JLPT N5, la marca de corte de aprobaci\u00f3n de cada secci\u00f3n son las siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vocabulario, gram\u00e1tica y comprensi\u00f3n lectora: <strong>38 puntos<\/strong><\/li>\n\n\n\n<li>Comprensi\u00f3n auditiva: <strong>19 puntos<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La nota general para aprobar es de <strong>80 puntos<\/strong> (el m\u00e1ximo es 180 puntos).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Registrarse para el examen<\/strong><\/h2>\n\n\n\n<p>Si te encuentras en Jap\u00f3n y deseas registrarse para el JLPT N5, puedes <a href=\"https:\/\/info.jees-jlpt.jp\/?lang=english\" target=\"_blank\" rel=\"noopener\">presentar tu solicitud online<\/a> unos tres o cuatro meses antes de la fecha del examen. Puedes leer m\u00e1s sobre el proceso en nuestro art\u00edculo <a href=\"https:\/\/gogonihon.com\/es\/blog\/todo-lo-que-necesitas-saber-sobre-presentarte-al-jlpt-en-japon\/\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<p>Si no est\u00e1s en Jap\u00f3n, deber\u00e1s encontrar el lugar del examen de tu pa\u00eds y registrarte con ellos directamente. Puedes encontrar una lista de los lugares del examen en el extranjero en el <a href=\"http:\/\/www.jlpt.jp\/e\/application\/overseas_list.html\" target=\"_blank\" rel=\"noopener\">sitio web oficial de JLPT<\/a>.<\/p>\n\n\n\n<p>La tarifa a pagar variar\u00e1 seg\u00fan la ubicaci\u00f3n y el nivel al que te presentes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"798\" height=\"436\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-30.png\" alt=\"Imagen de una estanter\u00eda con libros de estudio del idioma japon\u00e9s\" class=\"wp-image-187743\" srcset=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-30.png 798w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-30-300x164.png 300w, https:\/\/gogonihon.com\/wp-content\/uploads\/2023\/07\/GGN-Blog-Watermark-Rebrand-30-768x420.png 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Prepararse para el JLPT N5<\/strong><\/h2>\n\n\n\n<p>Ya sea que est\u00e9s aprendiendo japon\u00e9s en una escuela de idiomas, tomando un curso online o estudiando de forma autodidacta, el mejor consejo que podemos darte para aprobar el examen JLPT N5 es <strong>estudiar, estudiar y estudiar<\/strong>.<\/p>\n\n\n\n<p>El tiempo que te lleva dominar los requisitos de este examen es como preguntar cu\u00e1nto mide un trozo de cuerda: todos somos diferentes y aprendemos de manera diferente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Haz ex\u00e1menes de pr\u00e1ctica<\/strong><\/h3>\n\n\n\n<p><strong>Pon en pr\u00e1ctica las cosas que aprendes<\/strong>. Haz tantos ex\u00e1menes de pr\u00e1ctica como puedas. Aqu\u00ed te dejamos algunos recursos gratuitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jlpt.jp\/e\/samples\/forlearners.html\" target=\"_blank\" rel=\"noreferrer noopener\">P\u00e1gina JLPT<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/jlptsensei.com\/downloads\/jlpt-n5-practice-test\/\" target=\"_blank\" rel=\"noreferrer noopener\">JLPT Sensei<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/japanesetest4you.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Japanesetest4you<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/kanji123.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kanji123<\/a> (enfocado en kanji)<\/li>\n\n\n\n<li>Aplicaci\u00f3n para m\u00f3vil NHK &#8211; <a href=\"https:\/\/apps.apple.com\/us\/app\/easy-japanese-news-%E3%82%84%E3%81%95%E3%81%97%E3%81%84%E6%97%A5%E6%9C%AC%E8%AA%9E%E3%83%8B%E3%83%A5%E3%83%BC%E3%82%B9\/id1107177166\" target=\"_blank\" rel=\"noreferrer noopener\">Apple<\/a>, <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=mobi.eup.jpnews&amp;hl=en&amp;gl=US\" target=\"_blank\" rel=\"noreferrer noopener\">Google Play<\/a><\/li>\n<\/ul>\n\n\n\n<p>Puedes comprar el <a href=\"https:\/\/www.jlpt.jp\/e\/reference\/books.html\" target=\"_blank\" rel=\"noopener\">libro de pr\u00e1cticas oficial<\/a>, que es publicado por la misma organizaci\u00f3n que crea y administra la JLPT.<\/p>\n\n\n\n<p>Otros libros de preparaci\u00f3n del JLPT N5, como los creados por Nihongo Sou Matome, Shin Nihongo y TRY! tambi\u00e9n tendr\u00e1s preguntas de pr\u00e1ctica.<\/p>\n\n\n\n<p>Trata de imitar el entorno real del examen cuando realices ex\u00e1menes de pr\u00e1ctica. Esto significa respetar el l\u00edmite de tiempo, no distraerte y no hacer trampa ni buscar cosas. Hacer estos ex\u00e1menes de pr\u00e1ctica tambi\u00e9n te sirve para saber d\u00f3nde est\u00e1n las lagunas en tu conocimiento y qu\u00e9 necesitas trabajar m\u00e1s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Estudiar japon\u00e9s en Jap\u00f3n<\/strong><\/h3>\n\n\n\n<p>Estudiar japon\u00e9s en una escuela de idiomas en Jap\u00f3n es, con diferencia, una de las mejores formas de aprender el idioma y prepararse para el examen JLPT. Si tienes los medios para hacerlo, nada mejor que el <a href=\"https:\/\/gogonihon.com\/es\/blog\/aprende-japones-por-inmersion\/\">aprendizaje inmersivo<\/a> en el pa\u00eds donde se habla el idioma. Ir a clase todos los d\u00edas e interactuar con el idioma todo el tiempo significa que alcanzar\u00e1s tus metas de aprendizaje r\u00e1pidamente.<\/p>\n\n\n\n<p>Go! Go! Nihon te puede ayudar a solicitar plaza en escuelas de idiomas en Jap\u00f3n, adem\u00e1s, todas nuestras escuelas asociadas ofrecen cursos para principiantes. Muchas tambi\u00e9n ayudan a sus estudiantes a trabajar para los ex\u00e1menes JLPT.<\/p>\n\n\n\n<p>A partir de la convocatoria de octubre de 2026, se espera que los solicitantes de visados de estudiante demuestren su nivel de idioma mediante el <strong>resultado de un examen oficial<\/strong> (como el <a href=\"https:\/\/gogonihon.com\/es\/blog\/aprobar-el-jlpt-n5\/\">JLPT N5<\/a> o equivalente) o mediante una <strong>evaluaci\u00f3n o entrevista<\/strong> realizada por la escuela. Algunas escuelas pueden exigir ambos requisitos. Si cuentas con un t\u00edtulo universitario, es posible que quedes exento de algunos de estos requisitos.<\/p>\n\n\n\n<p>Visita nuestra <a href=\"https:\/\/gogonihon.com\/es\/escuelas-idiomas\/\">p\u00e1gina de escuelas<\/a> para ver las instituciones con las que nos asociamos en todo Jap\u00f3n y <a href=\"https:\/\/gogonihon.com\/es\/#ContactForm\">ponte en contacto<\/a> con nosotros si deseas comenzar con tu solicitud.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tomar un curso online<\/strong><\/h3>\n\n\n\n<p>Si no est\u00e1s estudiando en una escuela de idiomas, los cursos online son una excelente y econ\u00f3mica opci\u00f3n para prepararse para los ex\u00e1menes JLPT.<\/p>\n\n\n\n<p>El <a href=\"https:\/\/japaneseonline.gogonihon.com\/courses\/akamonkai-japanese-12-week-beginner-course\">curso para principiantes de 12 semanas de Go! Go! Nihon<\/a>, impartido en asociaci\u00f3n con la escuela de idioma japon\u00e9s Akamonkai, te ayudar\u00e1 a dominar todos los elementos esenciales del JLPT N5 en unas 150 horas de estudio. Este curso est\u00e1 dise\u00f1ado para personas con cero conocimiento del idioma; puedes realizarlo a tu propio ritmo y cuesta una fracci\u00f3n de lo que cuestan las escuelas de idiomas en Jap\u00f3n.<\/p>\n\n\n\n<p>Visita la <a href=\"https:\/\/japaneseonline.gogonihon.com\/courses\/akamonkai-japanese-12-week-beginner-course\">p\u00e1gina web del curso<\/a> para obtener m\u00e1s informaci\u00f3n e inscribirte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu\u00e9 esperar el d\u00eda del examen<\/strong><\/h2>\n\n\n\n<p>Antes del d\u00eda del examen, recibir\u00e1s un <em>voucher<\/em> de los organizadores. Este comprobante determinar\u00e1 en qu\u00e9 sala realizar\u00e1s el examen el d\u00eda de la prueba.<\/p>\n\n\n\n<p>En el aula del examen, solo se te permitir\u00e1 tener sobre el escritorio tus utensilios de escritura. Normalmente solo se te permitir\u00e1 usar l\u00e1piz y goma de borrar. Tambi\u00e9n puedes llevar contigo un reloj, pero debe ser anal\u00f3gico. Te recomendamos que traigas un reloj, ya que es posible que no haya relojes en la sala.<\/p>\n\n\n\n<p>Habr\u00e1 breves descansos entre cada secci\u00f3n del examen, que podr\u00e1s usar para ir al ba\u00f1o, salir a tomar un respiro o comer y beber algo.<\/p>\n\n\n\n<p>Cuando acabes el examen, tendr\u00e1s que esperar a que se recojan todos los ex\u00e1menes antes de poder salir del aula.<\/p>\n\n\n\n<p>Ten en cuenta que esto es solo una descripci\u00f3n general del proceso si est\u00e1s tomando el JLPT en Jap\u00f3n. Los procesos en los sitios de prueba en el extranjero pueden ser diferentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Cu\u00e1ndo esperar tus resultados<\/strong><\/h2>\n\n\n\n<p>Si est\u00e1s haciendo el examen en Jap\u00f3n, puedes esperar tener tus resultados en aproximadamente dos meses. Podr\u00e1s ver tus resultados a trav\u00e9s del portal online JLPT.<\/p>\n\n\n\n<p>Aquellos que realicen el examen fuera de Jap\u00f3n tendr\u00e1n sus resultados en dos o tres meses, aunque los detalles variar\u00e1n seg\u00fan el pa\u00eds.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Domina el JLPT N5 con Go! Go! Nihon<\/strong><\/h2>\n\n\n\n<p>El JLPT N5 puede ser el examen JLPT m\u00e1s f\u00e1cil de realizar, pero es una excelente manera de profundizar en los conceptos b\u00e1sicos esenciales del idioma. Adem\u00e1s, aprobar el examen es un logro del que puedes estar orgulloso.<\/p>\n\n\n\n<p>Go! Go! Nihon puede ayudarte a solicitar plaza en escuelas de idioma japon\u00e9s en Jap\u00f3n. Tambi\u00e9n ofrecemos una variedad de cursos online en colaboraci\u00f3n con algunas de las mejores escuelas de idiomas de Jap\u00f3n.<\/p>\n\n\n\n<p>Si tienes cualquier pregunta o quieres comenzar con tu solicitud, \u00a1no dudes en <a href=\"https:\/\/gogonihon.com\/es\/#ContactForm\">ponerte en contacto<\/a> con nosotros!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si est\u00e1s aprendiendo japon\u00e9s, probablemente hayas o\u00eddo hablar del Japanese Language Proficiency Test (JLPT o NOKEN). En esta serie de cinco partes, desglosaremos cada nivel de este examen, veremos de qu\u00e9 te evaluar\u00e1n, c\u00f3mo te calificar\u00e1n y c\u00f3mo puedes prepararte para este examen. En este primer art\u00edculo analizaremos el JLPT N5. \u00a1Sigue leyendo para saber [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":101002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[435],"tags":[1174,878],"class_list":["post-101011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos","tag-estudia","tag-idioma"],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/posts\/101011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/comments?post=101011"}],"version-history":[{"count":2,"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/posts\/101011\/revisions"}],"predecessor-version":[{"id":214663,"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/posts\/101011\/revisions\/214663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/media\/101002"}],"wp:attachment":[{"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/media?parent=101011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/categories?post=101011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gogonihon.com\/es\/wp-json\/wp\/v2\/tags?post=101011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}