{"id":31361,"date":"2019-10-02T15:00:56","date_gmt":"2019-10-02T06:00:56","guid":{"rendered":"https:\/\/gogonihon.com\/?p=31361"},"modified":"2024-02-22T08:48:07","modified_gmt":"2024-02-22T08:48:07","slug":"in-japan-zurechtfinden-die-japanische-adresse","status":"publish","type":"post","link":"https:\/\/gogonihon.com\/de\/blog\/in-japan-zurechtfinden-die-japanische-adresse\/","title":{"rendered":"In Japan zurechtfinden: Die japanische Adresse"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">W\u00e4hrend deines Aufenthalts in Japan wirst du sicherlich ab und zu mal einen Ort anhand der Adresse aufsuchen m\u00fcssen. Damit dir das ohne Probleme gelingt, erkl\u00e4ren wir dir in diesem Guide wie man eine japanische Adresse liest, versteht und mit ihr ans Ziel kommt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Japanische Adresse<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Schauen wir uns zuallererst die Struktur einer japanischen Adresse an. Einen Stra\u00dfennamen wirst du darin nicht finden (au\u00dfer bei Ausnahmen wie Kyoto und Sapporo) &#8211; ein gro\u00dfer Unterschied zu den Adressen, wie wir sie kennen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Reihenfolge ist ebenfalls anders: Eine japanische Adresse beginnt mit der Postleitzahl, darauf folgt das gr\u00f6\u00dfte geographische Element und zum Schluss kommt der spezifischste Teil, also die Hausnummer bzw. der Name.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>In R\u014dmaji schreiben<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wird die Adresse allerdings in <em>r\u014dmaji<\/em>, also in der romanisierten Version der <a href=\"https:\/\/gogonihon.com\/de\/blog\/japanische-schriftzeichen-und-alphabete\/\" target=\"_blank\" rel=\"noopener noreferrer\">japanischen Schriftzeichen<\/a> geschrieben, ist die Reihenfolge umgekehrt. Das hei\u00dft man f\u00e4ngt mit der Hausnummer an und endet mit Pr\u00e4fektur und Postleitzahl. Wenn du eine japanische Adresse in Google Maps eingibst, solltest du sie in dieser Reihenfolge schreiben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier als Beispiel mal die Schreibweise der Adresse des Go! Go! Nihon B\u00fcros in <em>r\u014dmaji<\/em> und in japanischen Zeichen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u014dmaji:&nbsp; 3-13-3 3F Seiwa Ikebukuro Geb\u00e4ude, Higashi-Ikebukuro, Toshima-ku, Tokyo-to 170-0013<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kanji:&nbsp;\u3012170-0013 \u6771\u4eac\u90fd\u8c4a\u5cf6\u533a\u6771\u6c60\u888b3-13-3 \u661f\u548c\u6c60\u888b\u30d3\u30eb 3\u968e<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gogonihon.com\/wp-content\/uploads\/2019\/06\/Map-GGN-office-min-932x1024.jpg\" alt=\"Map Go! Go! Nihon office\" class=\"wp-image-33987\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Als n\u00e4chstes schauen wir uns die Einzelteile der japanischen Adresse genauer an.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>1. Postleitzahl<br><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u3012170-0013<br>Das ist die Postleitzahl.&nbsp;\u3012 ist das Symbol f\u00fcr die <a href=\"https:\/\/gogonihon.com\/de\/blog\/post-aus-deutschland-ein-paket-nach-japan-schicken\/\" target=\"_blank\" rel=\"noopener noreferrer\">japanische Post<\/a> (und \u00e4hnelt dem <em>katakana&nbsp;<\/em>Zeichen \u30c6 te). Postleitzahlen in Japan bestehen aus 7 Ziffern. NNN-NNNN<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>2. Pr\u00e4fektur<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Japan ist in <strong>47 Pr\u00e4fekturen<\/strong> (\u770c, <em>ken<\/em>) aufgeteilt, und diese stellen den zweiten Teil einer jeden japanischen Adresse dar. Normalerweise wird die Pr\u00e4fektur \u770c (<em>ken<\/em>) genannt und auch so geschrieben, wie zum Beispiel die Pr\u00e4fektur Tochigi:&nbsp;\u6803\u6728\u770c (Tochigi-ken). Aber es gibt ein paar Ausnahmen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tokio wird nicht Pr\u00e4fektur, sondern Metropole (\u90fd, <em>to<\/em>) genannt und daher \u6771\u4eac\u90fd (Tokyo-to) geschrieben.<\/li>\n\n\n\n<li>Osaka und Kyoto werden als &#8222;Stadtpr\u00e4fekturen&#8220; (\u5e9c, <em>fu<\/em>) bezeichnet. Die Stadtpr\u00e4fektur Osaka w\u00fcrde man also \u5927\u962a\u5e9c (Osaka-fu) schreiben.<\/li>\n\n\n\n<li>Hokkaido ist zwar eine Pr\u00e4fektur, hat aber ein eigenes Suffix (\u9053, <em>d\u014d<\/em>), was &#8222;Bezirk&#8220; bedeutet. Das Suffix ist bereits im Namen enthalten: Hokkaido (\u5317\u6d77\u9053).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3. Stadtbezirk<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als n\u00e4chstes kommen Stadt (\u5e02, <em>shi<\/em>), Bezirk (\u533a, <em>ku<\/em>), oder Landkreis (\u90e1, <em>gun<\/em>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An St\u00e4dtenamen wird das Suffix (\u5e02) angeh\u00e4ngt, wie zum Beispiel bei der Stadt Yokohama (\u6a2a\u6d5c\u5e02,&nbsp;Yokohama-shi).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gro\u00dfst\u00e4dte werden au\u00dferdem in Stadtteile oder Bezirke eingeteilt. Tokio hat 23 &#8222;Sonder-Bezirke&#8220; (\u7279\u5225\u533a, <em>tokubetsu-ku<\/em>), die \u00fcblicherweise einfach nur als &#8222;Bezirke&#8220; bezeichnet&nbsp;(\u533a, ku) werden. Ein Beispiel daf\u00fcr w\u00e4re der bekannte Bezirk Shinjuku (\u65b0\u5bbf\u533a,&nbsp;Shinjuku-ku).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kleinere, weniger dicht besiedelte Gegenden werden Landkreise genannt (\u90e1, <em>gun<\/em>). Diese Bezeichnung wirst du vor allem bei den Adressen von l\u00e4ndlicheren Gegenden sehen, wie beispielsweise der Kreis Gunma (\u7fa4\u99ac\u90e1,&nbsp;Gunma-gun) in der Pr\u00e4fektur Gunma.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>4. Kleinst\u00e4dte\/D\u00f6rfer<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Viele japanische Adressen sind zus\u00e4tzlich in noch weitere kleinere Elemente aufgeteilt: Kleinst\u00e4dte (\u753a, <em>machi<\/em>\/<em>ch\u014d<\/em>) und D\u00f6rfer (\u6751, <em>mura\/son<\/em>).&nbsp;Sakuragi-ch\u014d (\u685c\u6728\u753a) in Yokohama w\u00e4re ein Beispiel f\u00fcr eine Kleinstadt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und jetzt mal ein Beispiel mit all den bisher erw\u00e4hnten Elementen zusammen: \u795e\u5948\u5ddd\u770c\u6a2a\u6d5c\u5e02\u4e2d\u533a\u685c\u6728\u753a bedeutet: Pr\u00e4fektur Kanagawa, Stadt Yokohama, Bezirk Naka, Kleinstadt Sakuragi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5. Stadtteilabschnitt<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Japanische St\u00e4dte werden au\u00dferdem noch in nummerierte Abschnitte (\u4e01\u76ee,&nbsp;<em>ch\u014dme<\/em>) unterteilt, die meistens basierend auf ihrer N\u00e4he zum Stadtzentrum bestimmt werden. \uff13\u4e01\u76ee (<em>san<\/em>&#8211;<em>ch\u014dme)<\/em> zum Beispiel w\u00e4re der dritte Stadtteilabschnitt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>6. Ortsteil\/Block<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem Abschnitt folgt die Blocknummer (\u756a\u5730, <em>banchi<\/em>). Diese werden einfach nach der Reihenfolge ihrer Registrierung nummeriert und k\u00f6nnen deswegen eine etwas zerstreute und unregelm\u00e4\u00dfige Anordnung haben.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>7. Hausnummer<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e4user und Geb\u00e4ude werden nat\u00fcrlich ebenfalls mit Nummern (\u53f7, <em>g\u014d<\/em>) versehen. Die Reihenfolge h\u00e4ngt jedoch nicht vom Grundst\u00fcck ab, sondern vom Bau des Hauses. Manchmal werden <em>g\u014d&nbsp;<\/em>auch einfach im Uhrzeigersinn vom Block vergeben. Daher muss die Abfolge nicht zwingend linear, sondern kann auch hier etwas unregelm\u00e4\u00dfig sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese drei Teile (Abschnitt, Block und Hausnummer) werden in der Regel nur mit den Nummern geschrieben, also 3-3-13 anstatt 3\u4e01\u76ee3\u756a\u573013\u53f7 (Stadtteilabschnitt 3, Block 3, Hausnummer 13).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>8. Geb\u00e4udename und -nummer<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das Geb\u00e4ude einen festgelegten Namen hat, schreibt man diesen hinter die Hausnummer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zum Beispiel befindet sich Ichiran Ramen in Shibuya an folgender Adresse: \u6771\u4eac\u90fd\u6e0b\u8c37\u533a\u795e\u5357\uff11\u4e01\u76ee22\u22127 \u5ca9\u672c\u30d3\u30ebB1F (Tokyo-to, Shibuya-shi, Jinnan, 1-ch\u014dme\u221222\u22127, Iwamoto biru B1F), also im Stock B1 des Iwamoto Geb\u00e4udes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn es sich bei der Adresse um eine Wohnung handelt, folgt nach der Haus- oder Geb\u00e4udenummer noch die Wohnungsnummer. Diese wird in der Regel einfach hinter die Zahlenabfolge von Abschnitt, Block und Hausnummer geschrieben. Wenn das vorherige Beispiel eine Wohnung w\u00e4re, k\u00f6nnte die Adresse so aussehen: 3-3-13-502. Die Wohnungsnummer w\u00e4re hier also die 502.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ausnahmen<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Zu guter Letzt gibt es noch ein paar Ausnahmef\u00e4lle. In Kyoto und Sapporo weicht das System eine japanische Adresse zu lesen leider ein wenig von der Norm ab. Die Details dazu kannst du <a href=\"https:\/\/de.wikipedia.org\/wiki\/Postadressen_in_Japan#Lokale_Besonderheiten\" target=\"_blank\" rel=\"noopener noreferrer\">in diesem Wikipedia Artikel<\/a> nachlesen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir hoffen dieser Guide hilft dir weiter, wenn du das n\u00e4chste Mal eine japanische Adresse finden musst, und dass du dich mit deinen neuen Kenntnissen in Japan jetzt besser zurechtfinden wirst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noch mehr n\u00fctzliche Tipps zum Leben in Japan findest du auf unserem <a href=\"https:\/\/gogonihon.com\/de\/blog\/\" target=\"_blank\" rel=\"noopener noreferrer\">Go! Go! Nihon Blog<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend deines Aufenthalts in Japan wirst du sicherlich ab und zu mal einen Ort anhand der Adresse aufsuchen m\u00fcssen. Damit dir das ohne Probleme gelingt, erkl\u00e4ren wir dir in diesem Guide wie man eine japanische Adresse liest, versteht und mit ihr ans Ziel kommt. Japanische Adresse Schauen wir uns zuallererst die Struktur einer japanischen Adresse [&hellip;]<\/p>\n","protected":false},"author":88,"featured_media":28344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[417],"tags":[806,818,1143],"class_list":["post-31361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tipps-und-tricks","tag-gesellschaft","tag-im-ausland-leben","tag-lernen-in-japan"],"_links":{"self":[{"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/posts\/31361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/comments?post=31361"}],"version-history":[{"count":0,"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/posts\/31361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/media\/28344"}],"wp:attachment":[{"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/media?parent=31361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/categories?post=31361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gogonihon.com\/de\/wp-json\/wp\/v2\/tags?post=31361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}